{"id":9244,"date":"2014-10-23T20:36:13","date_gmt":"2014-10-23T20:36:13","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=9244"},"modified":"2018-02-05T14:07:31","modified_gmt":"2018-02-05T19:07:31","slug":"la-mision-de-transformar-el-campo-colombiano","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/","title":{"rendered":"La misi\u00f3n de transformar el campo Colombiano"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Agricultura_Campo.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-9246\" title=\"Agricultura_Campo\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Agricultura_Campo-300x126.jpg\" alt=\"\" width=\"300\" height=\"126\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Agricultura_Campo-300x126.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Agricultura_Campo.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Con el sugestivo y bello t\u00edtulo de \u201cSaldar la deuda hist\u00f3rica con el campo\u201d, fue presentado el 14 de octubre de 2014 el informe sobre el marco conceptual de la Misi\u00f3n para la Transformaci\u00f3n del Campo, integrada por expertos en el sector rural y dirigida por el connotado economista Jos\u00e9 Antonio Ocampo.<\/p>\n<p style=\"text-align: justify;\">La necesidad de la transformaci\u00f3n ha sido planteada por el evidente atraso del desarrollo agropecuario, tanto con respecto a otros pa\u00edses latinoamericanos, como con respecto a la realidad de Colombia; por la crisis social rural evidenciada por el paro nacional agrario y otras grandes movilizaciones; y tambi\u00e9n por los planteamientos acordados en las negociaciones de paz, cuyo texto completo ha sido hecho p\u00fablico recientemente.\u00a0<!--more--><\/p>\n<p style=\"text-align: justify;\">Es muy importante el objetivo central de la Misi\u00f3n: proponer pol\u00edticas de Estado para que el pa\u00eds salde su deuda hist\u00f3rica con el campo, como elemento esencial para construir la paz. Hay un enfoque acertado sobre los principales problemas del sector, que desemboca en propuestas interesantes, pero que se contradice al tratar de algunas medidas concretas y es t\u00edmido frente a soluciones claves.<\/p>\n<p style=\"text-align: justify;\">Entre los aciertos esenciales el informe declara sin titubeos que el desmantelamiento de la red institucional de apoyo al sector rural ha tenido efectos devastadores. Verdad gigante: presupuesto p\u00fablico enano, destrucci\u00f3n del ICA, de la Caja Agraria y del Idema, miniaturizaci\u00f3n del Incora, destrucci\u00f3n del Servicio de Erradicaci\u00f3n de la Malaria, etc.<\/p>\n<p style=\"text-align: justify;\">Si se quiere imprimir otro dinamismo al sector y a la institucionalidad agropecuaria hay que partir de la generaci\u00f3n de tecnolog\u00eda. El informe saluda la reactivaci\u00f3n de Corpoica y la \u00e1nima, pero es muy t\u00edmido. Colombia requiere dedicar recursos sustanciales a la generaci\u00f3n de tecnolog\u00eda agropecuaria propia, limpia, adecuada a la diversidad geogr\u00e1fica y ecol\u00f3gica y a la heterogeneidad de las formas de producci\u00f3n, tama\u00f1o de propiedad y tenencia de la tierra. Se necesita un instituto y m\u00faltiples grupos de trabajo cient\u00edfico que generen tecnolog\u00eda y desde luego tambi\u00e9n que la transfieran en un pa\u00eds donde solamente el 4% de los campesinos tienen alguna asistencia t\u00e9cnica.<\/p>\n<p style=\"text-align: justify;\">Es necesario construir un sistema de planificaci\u00f3n agropecuaria, que pueda dirigir el cr\u00e9dito de fomento, la asistencia t\u00e9cnica, el mercadeo y el procesamiento de los productos. En este sentido, como bien lo han exigido las organizaciones campesinas, se requiere planificar y garantizar precios de sustentaci\u00f3n para orientar adecuadamente el desarrollo del sector y evitar que sea atrapado por la telara\u00f1a de los precios y la especulaci\u00f3n internacional.<\/p>\n<p style=\"text-align: justify;\">El informe dice con raz\u00f3n que el sector agropecuario del pa\u00eds \u201cenfrenta un volumen creciente de importaciones que han reducido el tradicional super\u00e1vit de la balanza comercial del sector\u201d. T\u00edmidamente a\u00f1ade que \u201cpueden ser necesarias algunas medidas de protecci\u00f3n, pero con una visi\u00f3n de largo plazo que busque aumentar la competitividad\u201d. Hay que llamar las cosas por su nombre. En verdad se necesita una pol\u00edtica de protecci\u00f3n de la producci\u00f3n nacional, que incluya la revisi\u00f3n de los tratados de libre comercio y que desde luego sea completada por la generaci\u00f3n de tecnolog\u00eda propia, el cr\u00e9dito de fomento y los precios de sustentaci\u00f3n. Hay que recuperar la soberan\u00eda alimentaria.<\/p>\n<p style=\"text-align: justify;\">Con toda la raz\u00f3n, la Misi\u00f3n afirma que es prioritario \u201clanzar una pol\u00edtica ambiciosa de ordenamiento social de la propiedad rural\u201d, la cual es \u201cparte adem\u00e1s de la instrumentaci\u00f3n de los acuerdos de paz\u201d. Aqu\u00ed no se trata solamente de un problema social de excesiva concentraci\u00f3n de la propiedad y de despojo por desplazamiento forzado, se trata adem\u00e1s de un problema econ\u00f3mico clave para Colombia y de un problema ecol\u00f3gico fundamental.<\/p>\n<p style=\"text-align: justify;\">El alto \u00edndice de concentraci\u00f3n de la propiedad en Colombia, significa un alto precio de la tierra, de manera que la renta de la tierra es un obst\u00e1culo grave para el desarrollo rural, la rentabilidad y la competitividad del sector. El problema m\u00e1s com\u00fan en Colombia no es comparar la productividad de la gran empresa con la de la agricultura familiar, sino comparar la ociosidad del latifundio que mantiene sin sembrar 16 millones de hect\u00e1reas aptas para la agricultura, con la laboriosidad de campesinos, ind\u00edgenas y afros que se ven obligados a cultivar tierras menos aptas y desde ah\u00ed abastecen de alimentos y desde hace d\u00e9cadas se destacan como exportadores que participan del mercado mundial.<\/p>\n<p style=\"text-align: justify;\">Este grave problema econ\u00f3mico del no cumplimiento de la funci\u00f3n social de la propiedad, se expresa tambi\u00e9n incumplimiento de la funci\u00f3n ecol\u00f3gica, como un grave problema ecol\u00f3gico, porque la no utilizaci\u00f3n o subutilizaci\u00f3n de las tierras aptas para la agricultura, desplaza al campesinado a tierras no aptas y sobreutilizadas, forzando la destrucci\u00f3n de los bosques y causando la invasi\u00f3n de territorios ind\u00edgenas.<\/p>\n<p style=\"text-align: justify;\">El ordenamiento social de la propiedad es urgente y no puede depender solamente de los acuerdos de paz, es una necesidad del pa\u00eds y de la mayor\u00eda de los colombianos, comenzando por los habitantes de las ciudades, especialmente los que est\u00e1n desnutridos, los que tienen carencia de prote\u00ednas y vitaminas y necesitan comida de calidad y ambiente sano.<\/p>\n<p style=\"text-align: justify;\">Aqu\u00ed hay que anotar las inconsecuencias m\u00e1s graves de la Misi\u00f3n. Una institucional, volver a la en\u00e9sima propuesta del reestructuraci\u00f3n o hasta (qu\u00e9 desprop\u00f3sito) \u201cliquidaci\u00f3n\u201d del Incoder (Incora). Cada reestructuraci\u00f3n ha costado dos a\u00f1os de par\u00e1lisis del ordenamiento social de la propiedad, por los costosos despidos y contrataciones nuevas, la elaboraci\u00f3n y ampliaci\u00f3n de nuevos decretos reglamentarios, los trasteos, las p\u00e9rdidas de memorias institucionales. Del Incora sali\u00f3 el Himat, que luego fue refusionado en 2003 junto con el Fondo Dri que ahora se propone separar y ampliar y junto con el instituto de pesca que ten\u00eda que haberse ampliado y fortalecido en lugar de matar y que se pas\u00f3 luego al ICA, cuando se descuartiz\u00f3 el Incoder en dos institutos de tierras que se refusionaron porque el Estatuto Rural era inconstitucional.<\/p>\n<p style=\"text-align: justify;\">Semejante enredo de fusiones y divisiones institucionales cada vez con menos presupuesto, deber\u00eda comenzar a resolverse d\u00e1ndole al Incoder la capacidad de cumplir sus funciones legales, tanto en lo que se refiere al presupuesto, como en lo que se refiere a las \u00f3rdenes de no constituir reservas campesinas, que son ley vigente y no s\u00f3lo ni principalmente asunto de acuerdos de paz.<\/p>\n<p style=\"text-align: justify;\">Tal vez ser\u00eda interesante tener un fuerte Incora que se encargue del tema tierras, un fuerte instituto de desarrollo rural y un gran instituto de pesca que por fin desarrolle ese sector clave para el futuro de Colombia. Pero comenzar por la reestructuradera ser\u00eda matar para siempre el ordenamiento social de la propiedad, al menos las funciones de tierras deben continuar en el mismo instituto.<\/p>\n<p style=\"text-align: justify;\">El otro asunto grave es el mico que quiere ir al hombro de una misi\u00f3n noble. La legalizaci\u00f3n del acaparamiento de bald\u00edos. La misi\u00f3n propone en primer lugar, que se \u201cinterprete\u201d que la prohibici\u00f3n de acumular bald\u00edos adjudicados a colonos campesinos solo se refiere a t\u00edtulos otorgados a partir de la vigencia de la ley 160 de 1994. Como lo ha dicho un concepto del Consejo de Estado, desde la ley 135 de 1961 el comercio de bald\u00edos era restringido y las adjudicaciones se limitaban a 450 hect\u00e1reas en tierras cultivadas y hasta 1.000 hect\u00e1reas en sabanas de pastos naturales. Desde la ley 30 de 1988 el l\u00edmite fue de 400 hect\u00e1reas y lo que hizo la ley 160 fue establecer que el l\u00edmite era la UAF, de diferente tama\u00f1o seg\u00fan la regi\u00f3n y que en los Llanos fue estirada por normas de Incoder a m\u00e1s de las 1.000 hect\u00e1reas en varios municipios. No se trata de retroactividad, sino de prohibiciones que establec\u00edan las leyes anteriores.<\/p>\n<p style=\"text-align: justify;\">Propone tambi\u00e9n el informe de la Misi\u00f3n \u201csanear\u201d la situaci\u00f3n creada por acumulaci\u00f3n ilegal de bald\u00edos adjudicados a colonos campesinos en virtud de la ley 160 de 1994, a trav\u00e9s de facilitar la creaci\u00f3n de Zonas de Desarrollo Empresarial con las tierras acaparadas por empresas y \u201cse aclare que en estos casos, y sobre tierras ya entregadas en propiedad, no se aplica la norma de acumulaci\u00f3n pero al mismo tiempo se exija la unidad de empresa\u201d. Y en el futuro crear esas Zonas \u201cen tierras que ser\u00edan arrendadas por per\u00edodos largos por el Estado m\u00e1s que entregadas en propiedad\u201d. Es decir, quienes violaron la ley podr\u00e1n consolidar propiedades en \u201cunidad de empresa\u201d. \u00bfC\u00f3mo as\u00ed? No se trata de un problema de mero saneamiento, sino de la generaci\u00f3n de una inmensa renta de la tierra en manos de unos pocos propietarios, cuyo negocio principal no ha sido ni es ni ser\u00e1 la producci\u00f3n agropecuaria sino la especulaci\u00f3n con los precios de la tierra.<\/p>\n<p style=\"text-align: justify;\">Para el futuro la recomendaci\u00f3n que supuestamente es de la Misi\u00f3n, ya se ha concretado en el proyecto ley 133 de 2014 (C\u00e1mara), la \u00fanica criatura que ya ha sido concebida en este proceso. En este proyecto el gobierno nacional insiste otra vez en que el problema de tierras se resuelve prioritariamente en los bald\u00edos de la Altillanura y no en utilizar la gran masa de tierras aptas para la agricultura, desperdiciadas en manos del latifundio. En el proyecto se reduce a s\u00f3lo una tercera parte el \u00e1rea que debe estar en aprovechamiento y a tres a\u00f1os el tiempo para adjudicar un bald\u00edo a un colono campesino y exige que \u00e9ste presente su declaraci\u00f3n de renta. \u00bfCu\u00e1ntos colonos campesinos presentan declaraci\u00f3n de renta? Ninguno.<\/p>\n<p style=\"text-align: justify;\">El proyecto 133 pretende en sus art\u00edculos 11 y 12 quebrar la prohibici\u00f3n de acumular tierras adjudicadas en propiedad como bald\u00edos y especialmente en el art\u00edculo 12 abre el paso a la acumulaci\u00f3n de bald\u00edos por grandes empresas en las que denomina \u201cZonas de Inter\u00e9s de Desarrollo Econ\u00f3mico y Social\u201d (ZIDES)\u201d, donde se adjudicar\u00e1n, adem\u00e1s, \u00e1reas solamente en arrendamiento, pero donde \u00a1Oh Gloria inmarcesible! se realizar\u00e1 tambi\u00e9n el acaparamiento en propiedad, de bald\u00edos previamente adjudicados a colonos campesinos. El art\u00edculo 13 a\u00f1ade la famosa interpretaci\u00f3n ya negada por el Consejo de Estado. Por favor, expertos respetables que integran la Misi\u00f3n, bajen ese mico de su hombro.<\/p>\n<p style=\"text-align: justify;\">Cuando en 2010 el entonces ministro Juan Camilo Restrepo present\u00f3 las conclusiones del estudio del IGAC sobre uso y aprovechamiento de tierras, pod\u00edan esperarse transformaciones positivas para el campo. Cuando se present\u00f3 y aprob\u00f3 la ley del plan de desarrollo, todo se redujo a atacar los bald\u00edos, a permitir su acaparamiento. La Corte Constitucional dijo NO.<\/p>\n<p style=\"text-align: justify;\">Ahora contamos con interesantes diagn\u00f3sticos de la Misi\u00f3n Rural 2014, que llega hasta se\u00f1alar las contradicciones que por el uso del suelo generan la miner\u00eda y la explotaci\u00f3n de hidrocarburos, que plantea la necesidad de una pol\u00edtica integral, mucho m\u00e1s all\u00e1 de lo agropecuario, para beneficiar a la poblaci\u00f3n rural, que plantea que sea el sujeto principal, que participe en las decisiones y programas. Por favor, no vuelvan a salir con que el plan estrella es entregarle los Llanos Orientales, la que llaman \u201cAltillanura\u201d, a las transnacionales.<\/p>\n<p>H\u00e9ctor Mondrag\u00f3n<\/p>\n<p>Consultor<\/p>\n<p>Edici\u00f3n N\u00b0 00421 \u2013 Semana del 17 al 23 de Octubre \u2013 2014<\/p>\n<p>http:\/\/www.viva.org.co\/cajavirtual\/svc0421\/articulo04.html<\/p>\n<p><a href=\"https:\/\/nasaacin.org\/informativo-nasaacin\/3-newsflash\/7180-la-misi%c3%b3n-de-transformar-el-campo-colombiano\">http:\/\/nasaacin.org\/informativo-nasaacin\/3-newsflash\/7180-la-misi%C3%B3n-de-transformar-el-campo-colombiano<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el sugestivo y bello t\u00edtulo de \u201cSaldar la deuda hist\u00f3rica con el campo\u201d, fue presentado el 14 de octubre de 2014 el informe sobre el marco conceptual de la Misi\u00f3n para la Transformaci\u00f3n del Campo, integrada por expertos en el sector rural y dirigida por el connotado economista Jos\u00e9 Antonio Ocampo. La necesidad de <\/p>\n","protected":false},"author":6,"featured_media":9246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La misi\u00f3n de transformar el campo Colombiano - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La misi\u00f3n de transformar el campo Colombiano - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"Con el sugestivo y bello t\u00edtulo de \u201cSaldar la deuda hist\u00f3rica con el campo\u201d, fue presentado el 14 de octubre de 2014 el informe sobre el marco conceptual de la Misi\u00f3n para la Transformaci\u00f3n del Campo, integrada por expertos en el sector rural y dirigida por el connotado economista Jos\u00e9 Antonio Ocampo. La necesidad de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-23T20:36:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-05T19:07:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Agricultura_Campo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"La misi\u00f3n de transformar el campo Colombiano\",\"datePublished\":\"2014-10-23T20:36:13+00:00\",\"dateModified\":\"2018-02-05T19:07:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/\"},\"wordCount\":1965,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/\",\"name\":\"La misi\u00f3n de transformar el campo Colombiano - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2014-10-23T20:36:13+00:00\",\"dateModified\":\"2018-02-05T19:07:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La misi\u00f3n de transformar el campo Colombiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La misi\u00f3n de transformar el campo Colombiano - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/","og_locale":"es_ES","og_type":"article","og_title":"La misi\u00f3n de transformar el campo Colombiano - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"Con el sugestivo y bello t\u00edtulo de \u201cSaldar la deuda hist\u00f3rica con el campo\u201d, fue presentado el 14 de octubre de 2014 el informe sobre el marco conceptual de la Misi\u00f3n para la Transformaci\u00f3n del Campo, integrada por expertos en el sector rural y dirigida por el connotado economista Jos\u00e9 Antonio Ocampo. La necesidad de","og_url":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2014-10-23T20:36:13+00:00","article_modified_time":"2018-02-05T19:07:31+00:00","og_image":[{"width":"900","height":"378","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Agricultura_Campo.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"La misi\u00f3n de transformar el campo Colombiano","datePublished":"2014-10-23T20:36:13+00:00","dateModified":"2018-02-05T19:07:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/"},"wordCount":1965,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/","url":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/","name":"La misi\u00f3n de transformar el campo Colombiano - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2014-10-23T20:36:13+00:00","dateModified":"2018-02-05T19:07:31+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/la-mision-de-transformar-el-campo-colombiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"La misi\u00f3n de transformar el campo Colombiano"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Agricultura_Campo.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/9244"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=9244"}],"version-history":[{"count":4,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/9244\/revisions"}],"predecessor-version":[{"id":19958,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/9244\/revisions\/19958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/9246"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=9244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=9244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=9244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}