{"id":9171,"date":"2014-10-16T03:48:40","date_gmt":"2014-10-16T03:48:40","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=9171"},"modified":"2014-10-16T03:48:40","modified_gmt":"2014-10-16T03:48:40","slug":"la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/","title":{"rendered":"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Congreso_11.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-medium wp-image-9173\" title=\"Congreso_1\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Congreso_11-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Congreso_11-300x198.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Congreso_11.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Con un saludo fraternal por parte de la Consejer\u00eda Mayor del CRIC a los congresistas y sobre todo a las diferentes organizaciones regionales ind\u00edgenas del Pa\u00eds, se dio inicio al tercer d\u00eda del Congreso Extraordinario del CRIC que se realiza en la Mar\u00eda Piendamo, Cauca Colombia. As\u00ed mismo, cada uno de los delegados de las regionales ind\u00edgenas expresaron su gratitud y solidaridad con las diferentes luchas que se libran en el Pa\u00eds en defensa de la vida y el territorio.<!--more--><\/p>\n<p style=\"text-align: justify;\">Luego de los saludos, se avanzo con la agenda de trabajo con exposiciones que tuvieron como objetivo orientar la discusi\u00f3n y reflexi\u00f3n en las comisiones, para que los pueblos y las comunidades ind\u00edgenas manifiesten sus preocupaciones y se proyecte el caminar del proceso organizativo.<\/p>\n<p style=\"text-align: justify;\">Los temas expuestos fueron los siguientes:<\/p>\n<p style=\"text-align: justify;\">Miner\u00eda, Defensa de la vida, conflicto armado y paz, derecho a \u00a0la comunicaci\u00f3n propia, tema agrario.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/LuisGaray_Congreso.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-9174\" title=\"LuisGaray_Congreso\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/LuisGaray_Congreso-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/LuisGaray_Congreso-300x200.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/LuisGaray_Congreso-1024x682.jpg 1024w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/LuisGaray_Congreso.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Luis Jorge Garay ambientalista, en su intervenci\u00f3n sobre el tema minero nos manifiesta sobre la Pol\u00edtica Neoliberal Extractivita y el acaparamiento de tierras y territorios que est\u00e1n implementando las multinacionales\u2026 \u201cLos recursos naturales son recursos p\u00fablicos que est\u00e1n siendo transferidos al capital extranjero y a la empresa privada, la renta minera en Colombia es de las m\u00e1s bajas de Latinoam\u00e9rica, eso indica que Colombia abus\u00f3 del poder estatal para la explotaci\u00f3n de los recursos naturales. Desde 2001 la Pol\u00edtica minera es un mecanismo de empobrecimiento de los pueblos y sectores sociales del pa\u00eds, el 23% de los ingresos de la naci\u00f3n viene de la explotaci\u00f3n minera y de los hidrocarburos, mientras que solo se paga un 4% de impuestos y regal\u00edas de miner\u00eda, por ese motivo es necesario que haya un pronunciamiento popular en defensa de un derecho fundamental como es el derecho a la consulta y a la consulta previa\u201d. Manifest\u00f3 en su intervenci\u00f3n Jorge Garay<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Aida-Marina_Congreso.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-medium wp-image-9175\" title=\"Aida Marina_Congreso\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Aida-Marina_Congreso-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Aida-Marina_Congreso-300x200.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Aida-Marina_Congreso-1024x682.jpg 1024w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Aida-Marina_Congreso.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En la siguiente exposici\u00f3n, Aida Quilcue nos comparte la realidad que viven los pueblos ind\u00edgenas, la violaci\u00f3n al territorio y los derechos humanos que siguen padeciendo las comunidades originarias y sectores sociales del Cauca y Colombia. Nos invita a reflexionar acerca\u00a0 del conflicto armado, ya que se\u00a0 habla de paz pero esto es una estrategia militar que utiliza el gobierno para seguir reclutando nuestros ni\u00f1os y j\u00f3venes\u00a0 quienes realmente han sido los m\u00e1s afectados en medio de este conflicto armado. Nos hace \u00e9nfasis en que \u00a0la Autonom\u00eda debe ser acompa\u00f1ada realmente en el verdadero ejercicio y ponerlo en pr\u00e1ctica en cada uno de los territorios con el fin de continuar el proceso de fortalecimiento del \u00a0gobierno propio de los pueblos originarios. Otro tema tratado\u00a0 fue el de la guardia ind\u00edgena ya que \u00a0es un mecanismo que las autoridades han venido reafirmando como ejercicio de resistencia civil, ellos contribuyen a la defensa del territorio y la autoridad. Finalmente \u00a0manifiesta que es necesario buscar estrategias que ayuden \u00a0a dinamizar los problemas por los que est\u00e1n atravesando las comunidades ind\u00edgenas e Invita a seguir en resistencia y lucha por el territorio para la pervivencia y permanencia de los pueblos originarios.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Vicente_Congreso.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-9176\" title=\"Vicente_Congreso\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Vicente_Congreso-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Vicente_Congreso-300x200.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Vicente_Congreso-1024x682.jpg 1024w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Vicente_Congreso.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El derecho a la comunicaci\u00f3n e informaci\u00f3n propia en defensa de la vida y el territorio tuvo su lugar en el Congreso Extraordinario del CRIC, como un elemento pol\u00edtico y transversal en el proceso ind\u00edgena del Cauca y Colombia. El Coordinador del Programa de Comunicaciones del CRIC Vicente Otero, enfatiza en la importancia de las formas de comunicaci\u00f3n propia y plantea que el Ministerio de las TIC solo nos puede ofrecer tecnolog\u00eda y entonces donde queda la comunicaci\u00f3n diferencial lo propio de los pueblos ind\u00edgenas. Seguidamente contamos con la intervenci\u00f3n de Martin Vidal quien explica como ha sido el proceso de construcci\u00f3n de la Pol\u00edtica P\u00fablica de comunicaci\u00f3n ind\u00edgena y de entender que este elemento es una estrategia que ayuda en los procesos de resistencia y lucha, adem\u00e1s de contribuir con el fortalecimiento de la identidad cultural, la permanencia y pervivencia de los pueblos \u00a0originarios. Nos plantea como se construyeron los cuatro componentes de la pol\u00edtica p\u00fablica<\/p>\n<p style=\"text-align: justify;\">1. Formas propias de comunicaci\u00f3n ind\u00edgena. Los pueblos ind\u00edgenas queremos un pa\u00eds que posibilite el desarrollo de las formas propias de comunicaci\u00f3n ind\u00edgena y las fortalezca progresivamente, tales como espacios de pensamiento, la palabra y la organizaci\u00f3n comunitaria son formas especiales y propias de comunicaci\u00f3n<\/p>\n<p style=\"text-align: justify;\">2. Plan de formaci\u00f3n para los comunicadores ind\u00edgenas; la formaci\u00f3n para la comunicaci\u00f3n ind\u00edgena es una estrategia vital para la pol\u00edtica y existen importantes estrategias de formaci\u00f3n para la comunicaci\u00f3n ind\u00edgena\u00a0 en pleno desarrollo como resultado de la gesti\u00f3n de las organizaciones ind\u00edgenas mas no como resultado de una acci\u00f3n gubernamental.<\/p>\n<p style=\"text-align: justify;\">3. Medios apropiados; las condiciones actuales para el acceso y sostenimiento de los medios tecnol\u00f3gicos apropiados deben ser equitativas y justas para los pueblos ind\u00edgenas el acceso a los recursos tecnol\u00f3gicos y conectividad debe tener un trato equitativo y diferente paro los pueblos ind\u00edgenas.<\/p>\n<p style=\"text-align: justify;\">4. Derechos y garant\u00edas para la comunicaci\u00f3n ind\u00edgena; el derecho a la comunicaci\u00f3n ind\u00edgena se entiende no solo como una exigencia de enfoque diferencial desde la institucionalidad sino como la garant\u00eda para ejercer con autodeterminaci\u00f3n de manera libre el desarrollo de sus formas propias de comunicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Otros de los temas, de socializaci\u00f3n y evaluaci\u00f3n la realiz\u00f3 el Consejero Carlos S\u00e1nchez quien hizo una reflexi\u00f3n acerca de los decretos que se tocaron en la minga del 20013, enfatizo en la seguridad jur\u00eddica territorial, la protecci\u00f3n de los territorios ancestrales, la legalizaci\u00f3n de los t\u00edtulos coloniales y compra de las tierras. De la misma forma se espera que durante este semana en el marco del congreso extraordinario del CRIC se concrete las dem\u00e1s exigencias de los pueblos ind\u00edgenas.<\/p>\n<p style=\"text-align: justify;\">En horas de la noche se presentaron video foros por parte del Programa de Comunicaciones del CRIC, Red AMCIC y el Tejido de \u00a0comunicaciones de la ACIN, con proyecciones que mostro las \u00a0\u00a0experiencias productivas de las comunidades y la proyecci\u00f3n del CRIC hacia los 50 a\u00f1os de organizaci\u00f3n y permanencia en el territorio, con el fin de seguir caminando en el proceso de lucha y resistencia\u00a0 de los pueblos originarios, adem\u00e1s contamos con la participaci\u00f3n activa de \u00a0actos culturales donde participaron ni\u00f1os, ni\u00f1as, j\u00f3venes y mujeres mostrando una vez m\u00e1s\u00a0 la danza, la m\u00fasica tradicional y el arte de los pueblos ind\u00edgenas.<\/p>\n<p align=\"center\"><strong>CONSEJO REGIONAL IND\u00cdGENA DEL CAUCA \u2013CRIC-<\/strong><\/p>\n<p align=\"center\"><strong>Estudiantes de Comunicaci\u00f3n propia e Intercultural, Programa de Comunicaciones CRIC, Red AMCIC<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un saludo fraternal por parte de la Consejer\u00eda Mayor del CRIC a los congresistas y sobre todo a las diferentes organizaciones regionales ind\u00edgenas del Pa\u00eds, se dio inicio al tercer d\u00eda del Congreso Extraordinario del CRIC que se realiza en la Mar\u00eda Piendamo, Cauca Colombia. As\u00ed mismo, cada uno de los delegados de las <\/p>\n","protected":false},"author":6,"featured_media":9173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"Con un saludo fraternal por parte de la Consejer\u00eda Mayor del CRIC a los congresistas y sobre todo a las diferentes organizaciones regionales ind\u00edgenas del Pa\u00eds, se dio inicio al tercer d\u00eda del Congreso Extraordinario del CRIC que se realiza en la Mar\u00eda Piendamo, Cauca Colombia. As\u00ed mismo, cada uno de los delegados de las\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-16T03:48:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Congreso_11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"596\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios\",\"datePublished\":\"2014-10-16T03:48:40+00:00\",\"dateModified\":\"2014-10-16T03:48:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/\"},\"wordCount\":1156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena del Cauca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/\",\"name\":\"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2014-10-16T03:48:40+00:00\",\"dateModified\":\"2014-10-16T03:48:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/","og_locale":"es_ES","og_type":"article","og_title":"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"Con un saludo fraternal por parte de la Consejer\u00eda Mayor del CRIC a los congresistas y sobre todo a las diferentes organizaciones regionales ind\u00edgenas del Pa\u00eds, se dio inicio al tercer d\u00eda del Congreso Extraordinario del CRIC que se realiza en la Mar\u00eda Piendamo, Cauca Colombia. As\u00ed mismo, cada uno de los delegados de las","og_url":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2014-10-16T03:48:40+00:00","og_image":[{"width":"900","height":"596","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Congreso_11.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios","datePublished":"2014-10-16T03:48:40+00:00","dateModified":"2014-10-16T03:48:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/"},"wordCount":1156,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena del Cauca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/","url":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/","name":"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2014-10-16T03:48:40+00:00","dateModified":"2014-10-16T03:48:40+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/la-autonomia-como-verdadero-ejercicio-practico-en-los-territorios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"La Autonom\u00eda como verdadero ejercicio pr\u00e1ctico en los territorios"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/10\/Congreso_11.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/9171"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=9171"}],"version-history":[{"count":2,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/9171\/revisions"}],"predecessor-version":[{"id":9178,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/9171\/revisions\/9178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/9173"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=9171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=9171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=9171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}