{"id":8971,"date":"2014-09-25T21:35:21","date_gmt":"2014-09-25T21:35:21","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=8971"},"modified":"2018-05-18T18:37:15","modified_gmt":"2018-05-18T23:37:15","slug":"bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/","title":{"rendered":"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\"><strong><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-8973\" title=\"Estado_Plurinacional_Bolivia\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia-300x240.jpg\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia-300x240.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia-386x308.jpg 386w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La ley de la Madre Tierra y Desarrollo Integral para Vivir Bien, promulgada por el presidente del Estado, Evo Morales, el 15 de octubre,\u00a0 prohibe la concentraci\u00f3n de la propiedad de la tierra y el latifundio;\u00a0 el uso de transg\u00e9nicos en Bolivia y crea un fondo de justicia clim\u00e1tica.<\/strong><\/p>\n<p style=\"text-align: justify;\">En el mes de septiembre de 2012 se aprob\u00f3 en la Asamblea Legislativa del Estado Plurinacional de Bolivia laLey Marco de la Madre Tierra y Desarrollo Integral para Vivir Bien<strong>\u00a0<\/strong>y fue promulgada el 15 de octubre reciente, despu\u00e9s de varios a\u00f1os de debate en el \u00d3rgano Legislativo y entre las organizaciones sociales con respecto a su contenido.<\/p>\n<p style=\"text-align: justify;\">Una primera versi\u00f3n completa de la Ley con el nombre de \u201cLey Marco de la Madre Tierra\u201d fue acordada el a\u00f1o 2010 por las organizaciones sociales, A finales de ese a\u00f1o se aprob\u00f3 en la Asamblea Legislativa Plurinacional una parte del Proyecto de Ley con el titulo de Ley de Derechos de la Madre Tierra No. 071, dejando la segunda parte del proyecto de ley sujeto a debate en un per\u00edodo posterior.<!--more--><\/p>\n<p style=\"text-align: justify;\">La Ley de la Madre Tierra y Desarrollo Integral para Vivir Bien fue aprobada como ley marco, constituyendo en consecuencia la disposici\u00f3n matriz que dar\u00e1 a luz a las normas legales especiales a ser trabajadas en los pr\u00f3ximos a\u00f1os.<\/p>\n<p style=\"text-align: justify;\"><strong>Articulaci\u00f3n del Vivir bien, el desarrollo integral y los derechos de la Madre Tierra<\/strong><\/p>\n<p style=\"text-align: justify;\">La Ley define al Vivir Bien como el horizonte civilizatorio y cultural alternativo al capitalismo, que significa la construcci\u00f3n de un nuevo orden ambiental, social, cultural y econ\u00f3mico basado y emergente de la visi\u00f3n hist\u00f3rica de los pueblos ind\u00edgenas. Textualmente esta Ley expresa que este horizonte civilizatorio \u201cnace en las cosmovisiones de las naciones y pueblos ind\u00edgena originarios campesinos y las comunidades interculturales y afrobolivianas\u201d (Art. 5, numeral 2). Ahora bien, al tener este proyecto de vida su fundamento en los pueblos ind\u00edgenas y originarios, el mismo se enriquece y desarrolla en el marco de la interculturalidad y el di\u00e1logo de saberes, por lo que debe construirse en complementariedad con todos los pueblos y sociedades que habitan en el pa\u00eds. Esta visi\u00f3n es importante porque promueve la construcci\u00f3n de una sociedad intercultural respetando las diferencias y fortaleciendo a los pueblos y naciones ind\u00edgenas en el marco de la solidaridad y de su interdependencia con el conjunto del pueblo boliviano en lo que hace a la realizaci\u00f3n de los derechos colectivos y la erradicaci\u00f3n de la pobreza.<\/p>\n<p style=\"text-align: justify;\">El desarrollo integral es la implementaci\u00f3n de medidas y acciones integrales (econ\u00f3micas, sociales, espirituales, ambientales, culturales, materiales, entre otras) para el fortalecimiento y la creaci\u00f3n de condiciones materiales y espirituales que faciliten y fortalezcan el vivir bien de los pueblos y las sociedades. Entonces no es un desarrollo sin\u00f3nimo de progreso ni de corte occidental. Por el contrario, se establece que \u00e9stas medidas y acciones deben ser culturalmente adecuadas a la realidad de los pueblos, correspondiendo a sus culturas y construyendo v\u00ednculos edificantes, es decir, acciones y actitudes constructivas que sienten las bases para una sociedad equitativa, justa y solidaria.<\/p>\n<p style=\"text-align: justify;\">La Madre Tierra es el sistema viviente din\u00e1mico conformado por la comunidad indivisible de todos los sistemas de vida y los seres vivos, interrelacionados, interdependientes y complementarios, que comparten un destino com\u00fan. La Madre Tierra es considerada sagrada; alimenta y es el hogar que contiene, sostiene y reproduce a todos los seres vivos, los ecosistemas, la biodiversidad, las sociedades org\u00e1nicas y los individuos que la componen. En este contexto se reconocen los derechos de la Madre Tierra<\/p>\n<p style=\"text-align: justify;\">Entonces, la Ley Marco articula tres aspectos fundamentales: Vivir Bien, Madre Tierra y desarrollo integral; por lo que en la Ley se toma la decisi\u00f3n de no separar el \u201cdesarrollo integral\u201d, que se lo adec\u00faa a la realidad boliviana, con el del Vivir Bien, promovi\u00e9ndose m\u00e1s bien que el desarrollo integral sea una fase intermedia para alcanzar el Vivir Bien. Por lo mismo, desarrollo integral y Vivir Bien no son consideradas dos v\u00edas paralelas sino parte de un mismo camino, donde las acciones del primero ayudan a alcanzar el segundo que es el fin m\u00e1ximo. Sin embargo, es alrededor de la Madre Tierra que se promueve este proceso de articulaci\u00f3n, ya que la misma articula a la naturaleza y a los seres humanos.<\/p>\n<p style=\"text-align: justify;\"><strong>Complementariedad de derechos como la base de la convivencia arm\u00f3nica entre el pueblo boliviano, las naciones y pueblos ind\u00edgenas originarios y campesinas y la Madre Tierra<\/strong><\/p>\n<p style=\"text-align: justify;\">En la Ley Marco se considera fundamental el respeto y el reconocimiento de los derechos de los pueblos ind\u00edgena originario campesinos, pero tambi\u00e9n se reconoce que el conjunto del pueblo boliviano debe igualmente gozar de los beneficios de las riquezas que provee la Madre Tierra, las mismas que en el marco de un aprovechamiento sustentable y arm\u00f3nico, deben ser distribuidas y redistribuidas por el Estado Plurinacional, considerando adem\u00e1s la construcci\u00f3n de una sociedad justa, equitativa y solidaria sin pobreza material, social y espiritual.<\/p>\n<p style=\"text-align: justify;\">Bolivia tiene cerca de 12 millones de habitantes, de los cuales m\u00e1s de 5 viven en condiciones de pobreza y donde una gran parte de esta poblaci\u00f3n se encuentra en las \u00e1reas urbanas. La soluci\u00f3n a la falta de acceso a servicios, salud, educaci\u00f3n, energ\u00eda, comunicaci\u00f3n, as\u00ed como al acceso a alimentos, a los medios que permiten mejorar las oportunidades de creaci\u00f3n de condiciones materiales y el fortalecimiento de condiciones espirituales para Vivir Bien, requiere un esfuerzo gubernamental y social para el desarrollo de acciones e inversiones que implican el acceso y disponibilidad de recursos financieros por parte del Estado.<\/p>\n<p style=\"text-align: justify;\">Entonces, en Bolivia no se puede erradicar la pobreza ni garantizar los derechos fundamentales (civiles, pol\u00edticos, sociales, econ\u00f3micos y culturales) de las personas si es que no se cuenta con un Estado Plurinacional fuerte y con capacidades para emprender este desaf\u00edo; por lo menos en un escenario donde nuestro pa\u00eds es soberano y no dependiente. La propia ley expresa en su art\u00edculo 11, numeral 1, que es obligaci\u00f3n del Estado Plurinacional crear las condiciones para garantizar su propio sostenimiento.<\/p>\n<p style=\"text-align: justify;\">En esta l\u00ednea de reflexi\u00f3n la Ley ha establecido que el Vivir Bien se alcanza promoviendo y fortaleciendo cuatro derechos:<\/p>\n<p style=\"text-align: justify;\">Los derechos de la Madre Tierra.<\/p>\n<p style=\"text-align: justify;\">Los derechos de las naciones y pueblos ind\u00edgenas originarios y campesinos, comunidades interculturales y afrobolivianas.<\/p>\n<p style=\"text-align: justify;\">Los derechos civiles, pol\u00edticos, sociales, econ\u00f3micos y culturales del pueblo boliviano satisfaciendo las necesidades de las sociedades y personas.<\/p>\n<p style=\"text-align: justify;\">El derecho de la poblaci\u00f3n urbana y rural a vivir en una sociedad justa, equitativa y solidaria, sin pobreza material, social y espiritual.<\/p>\n<p style=\"text-align: justify;\">Estos derechos no pueden sobreponerse unos sobre otros o priorizarse uno sobre otro, al contrario, deben realizarse de manera complementaria, compatible, solidaria e interdependiente. Este es el m\u00e1ximo balance que propone la Ley para la construcci\u00f3n del Vivir Bien.<\/p>\n<p style=\"text-align: justify;\"><strong>Objetivos, bases y orientaciones del Vivir Bien a trav\u00e9s del desarrollo integral<\/strong><\/p>\n<p style=\"text-align: justify;\">Toda vez que el desarrollo integral es una fase intermedia hacia el Vivir Bien, la Ley ha establecido 10 (diez) objetivos y 11 (once) bases y orientaciones del desarrollo integral, en el marco de los Valores del Vivir Bien: saber crecer, saber alimentarse, saber danzar, saber trabajar, saber comunicarse, saber so\u00f1ar, saber escuchar, y saber pensar.<\/p>\n<p style=\"text-align: justify;\">Entre algunos de los objetivos tenemos el relacionado con \u201cel saber alimentarse para Vivir Bien\u201d que es la realizaci\u00f3n del derecho a la alimentaci\u00f3n en el marco de la soberan\u00eda con seguridad alimentaria, por el que se establece la importancia de fortalecer los sistemas econ\u00f3micos, productivos y ecol\u00f3gicos locales as\u00ed como el fortalecimiento y revalorizaci\u00f3n de los sistemas de vida de los peque\u00f1os productores, las naciones y pueblos ind\u00edgenas originarios y campesinos, comunidades interculturales y afrobolivianas. Otro objetivo promueve el cambio de patrones de consumo no sustentables, el uso racional de energ\u00eda, la conservaci\u00f3n del agua, la eliminaci\u00f3n del consumismo, y el aprovechamiento sustentable de los componentes de la Madre Tierra. Tambi\u00e9n existe el objetivo del cambio de los patrones de producci\u00f3n contaminantes, fortaleciendo los sistemas productivos compatibles con las zonas y sistemas de vida y mayor calidad ambiental. El objetivo que promueve la conservaci\u00f3n y el manejo integral y sustentable de la Madre Tierra establece igualmente el fortalecimiento de las \u00e1reas protegidas.<\/p>\n<p style=\"text-align: justify;\">Las orientaciones de la Ley tambi\u00e9n son muy importantes. Por ejemplo, con respecto a agricultura es notable que se establezca el desarrollo de acciones de protecci\u00f3n del patrimonio gen\u00e9tico \u201c\u2026prohibiendo la introducci\u00f3n, producci\u00f3n, uso, liberaci\u00f3n al medio y comercializaci\u00f3n de semillas gen\u00e9ticamente modificadas en el territorio de Estado Plurinacional de Bolivia de las que Bolivia es centro de origen o diversidad y de aquellas que atenten contra el patrimonio gen\u00e9tico, la biodiversidad\u2026los sistemas de vida y la salud humana.\u201d Asimismo, se establece que se deben desarrollar acciones \u201c\u2026que promuevan la eliminaci\u00f3n gradual de cultivos de organismos gen\u00e9ticamente modificados autorizados en el pa\u00eds\u2026\u201d. (Art 24, numeral 7 y 8)<\/p>\n<p style=\"text-align: justify;\">Con respecto a los bosques se establece que se proh\u00edbe \u201cde manera absoluta la conversi\u00f3n de uso de suelos de bosque a otros usos en zonas de vida de aptitud forestal, excepto cuando se trata de inter\u00e9s nacional y utilidad p\u00fablica\u201d (art. 25, numeral 4). Esta \u00faltima disposici\u00f3n obliga a emitir una Ley especial para cada caso relacionado con el cambio de uso del suelo con una justificaci\u00f3n de dicho inter\u00e9s nacional y utilidad p\u00fablica.<\/p>\n<p style=\"text-align: justify;\"><strong>Consejo Plurinacional para Vivir Bien y la Autoridad Plurinacional de la Madre Tierra<\/strong><\/p>\n<p style=\"text-align: justify;\">Con relaci\u00f3n al marco institucional que crea la Ley encargada de operacionalizar y dar sostenibilidad a la gesti\u00f3n p\u00fablica del desarrollo integral es importante de destacar: i) la creaci\u00f3n de un Consejo Plurinacional para Vivir Bien en Armon\u00eda y Equilibrio con la Madre Tierra que se constituye en una instancia de seguimiento, consulta y elaboraci\u00f3n participativa de pol\u00edticas, planes, programas y proyectos; ii) la creaci\u00f3n de la Autoridad Plurinacional de la Madre Tierra, como una entidad estrat\u00e9gica y aut\u00e1rquica, que tiene competencias en planificaci\u00f3n, gesti\u00f3n, monitoreo y evaluaci\u00f3n sobre cambio clim\u00e1tico, adem\u00e1s de administrar y ejecutar pol\u00edticas y estrategias, planes y programas relacionados con el mismo; y iii) Mecanismos dependientes de esta Autoridad Plurinacional para desarrollar intervenciones en mitigaci\u00f3n y adaptaci\u00f3n al cambio clim\u00e1tico, incluyendo el Fondo Plurinacional de la Madre Tierra como un mecanismo financiero que tiene la funci\u00f3n de administrar, canalizar y asignar recursos financieros en coordinaci\u00f3n con el Banco Central de Bolivia.<\/p>\n<p style=\"text-align: justify;\"><strong>Mecanismos de mitigaci\u00f3n y adaptaci\u00f3n al cambio clim\u00e1tico<\/strong><\/p>\n<p style=\"text-align: justify;\">La ley establece la creaci\u00f3n de tres Mecanismos para la gesti\u00f3n de la adaptaci\u00f3n y la mitigaci\u00f3n clim\u00e1tica, de acuerdo al siguiente detalle:<\/p>\n<p style=\"text-align: justify;\">Mecanismo Conjunto de Mitigaci\u00f3n y Adaptaci\u00f3n para el Manejo Integral de los Bosques y la Madre Tierra. Tiene el objetivo de fortalecer, conservar y proteger los sistemas de vida y sus funciones ambientales promoviendo y fortaleciendo la gesti\u00f3n social y comunitaria integral y sustentable de los bosques en el marco de metas conjuntas de mitigaci\u00f3n y adaptaci\u00f3n de los bosques. Se trata de un mecanismo no basado en mercados de carbono, y se constituye precisamente en el instrumento alternativo a los mercados de carbono en el contexto de REDD+ que Bolivia propuso en la COP 17 en Sudafrica en la Conferencia Mundial de Naciones Unidas sobre Cambio Clim\u00e1tico logrando.<\/p>\n<p style=\"text-align: justify;\">Mecanismo de Mitigaci\u00f3n para Vivir Bien. Est\u00e1 orientado a fortalecer y promover acciones de mitigaci\u00f3n clim\u00e1tica, incluyendo reducciones, limitaciones y acciones que eviten las emisiones de gases de efecto invernadero en distintas actividades industriales, productivas y energ\u00e9ticas entre otras.<\/p>\n<p style=\"text-align: justify;\">Mecanismo de Adaptaci\u00f3n para Vivir Bien. Est\u00e1 orientado a gestionar los procesos de adaptaci\u00f3n al cambio clim\u00e1tico en el marco de proyectos.<\/p>\n<p style=\"text-align: justify;\"><strong>Conclusiones<\/strong><\/p>\n<p style=\"text-align: justify;\">Como se ha destacado la Ley articula el Vivir bien, el desarrollo integral y los derechos de la Madre Tierra definiendo orientaciones para la gesti\u00f3n p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Esta Ley constituye una norma de gran envergadura que generar\u00e1 cambios fundamentales en el pa\u00eds, donde un aspecto fundamental es el establecimiento de cuatro derechos compatibles que permiten crear el escenario para alcanzar el Vivir Bien a trav\u00e9s del desarrollo integral. La complementariedad e interdependencia de estos derechos son la base de la convivencia arm\u00f3nica entre el pueblo boliviano, los pueblos y naciones ind\u00edgenas y originarias y campesinas con la naturaleza. Asimismo, la Ley establece las orientaciones pol\u00edticas, t\u00e9cnicas y legales para garantizar el sostenimiento de las capacidades de regeneraci\u00f3n de la Madre Tierra en el marco del desarrollo integral.<\/p>\n<p style=\"text-align: justify;\">Esta Ley establece las orientaciones filos\u00f3ficas pero tambi\u00e9n pr\u00e1cticas para la construcci\u00f3n del Estado Plurinacional de Bolivia en el marco de la implementaci\u00f3n de los mandatos de la Constituci\u00f3n Pol\u00edtica del Estado. Asimismo, es importante destacar el rol y los fundamentos jur\u00eddicos, pol\u00edticos e ideol\u00f3gicos que los pueblos y naciones ind\u00edgenas y originarias han dotado a esta norma.<\/p>\n<p><strong>Ren\u00e9 Orellana Halkyer y Diego Pacheco Balanza<\/strong><\/p>\n<p>http:\/\/www.elciudadano.cl\/2012\/10\/16\/58629\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ley de la Madre Tierra y Desarrollo Integral para Vivir Bien, promulgada por el presidente del Estado, Evo Morales, el 15 de octubre,\u00a0 prohibe la concentraci\u00f3n de la propiedad de la tierra y el latifundio;\u00a0 el uso de transg\u00e9nicos en Bolivia y crea un fondo de justicia clim\u00e1tica. En el mes de septiembre de <\/p>\n","protected":false},"author":6,"featured_media":8973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"La ley de la Madre Tierra y Desarrollo Integral para Vivir Bien, promulgada por el presidente del Estado, Evo Morales, el 15 de octubre,\u00a0 prohibe la concentraci\u00f3n de la propiedad de la tierra y el latifundio;\u00a0 el uso de transg\u00e9nicos en Bolivia y crea un fondo de justicia clim\u00e1tica. En el mes de septiembre de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-25T21:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-18T23:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio\",\"datePublished\":\"2014-09-25T21:35:21+00:00\",\"dateModified\":\"2018-05-18T23:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/\"},\"wordCount\":2258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena Global\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/\",\"name\":\"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2014-09-25T21:35:21+00:00\",\"dateModified\":\"2018-05-18T23:37:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/","og_locale":"es_ES","og_type":"article","og_title":"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"La ley de la Madre Tierra y Desarrollo Integral para Vivir Bien, promulgada por el presidente del Estado, Evo Morales, el 15 de octubre,\u00a0 prohibe la concentraci\u00f3n de la propiedad de la tierra y el latifundio;\u00a0 el uso de transg\u00e9nicos en Bolivia y crea un fondo de justicia clim\u00e1tica. En el mes de septiembre de","og_url":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2014-09-25T21:35:21+00:00","article_modified_time":"2018-05-18T23:37:15+00:00","og_image":[{"width":"900","height":"720","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio","datePublished":"2014-09-25T21:35:21+00:00","dateModified":"2018-05-18T23:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/"},"wordCount":2258,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena Global"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/","url":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/","name":"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2014-09-25T21:35:21+00:00","dateModified":"2018-05-18T23:37:15+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/bolivia-prohibe-transgenicos-en-su-territorio-y-el-latifundio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Bolivia prohibe transg\u00e9nicos en su territorio y el latifundio"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2014\/09\/Estado_Plurinacional_Bolivia.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/8971"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=8971"}],"version-history":[{"count":3,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/8971\/revisions"}],"predecessor-version":[{"id":21526,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/8971\/revisions\/21526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/8973"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=8971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=8971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=8971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}