{"id":42319,"date":"2025-04-30T16:50:37","date_gmt":"2025-04-30T21:50:37","guid":{"rendered":"https:\/\/www.cric-colombia.org\/portal\/?p=42319"},"modified":"2025-04-30T16:50:37","modified_gmt":"2025-04-30T21:50:37","slug":"mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/","title":{"rendered":"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Comunicado a la Opini\u00f3n P\u00fablica Nacional e Internacional<\/strong><\/p>\n<p style=\"text-align: justify;\">El Consejo Regional Ind\u00edgena del Cauca CRIC, con sus 138 autoridades tradicionales y 11 Asociaciones de cabildos pertenecientes a once Pueblos Ind\u00edgenas (Totoroez, Nasas, Misak, Kokonukos, Yanakonas Polindara, Ampiule, Kisgo, Eperara-Siapirara, Inga), ante el incumplimiento sistem\u00e1tico de parte de la Secretar\u00eda de Educaci\u00f3n de la Gobernaci\u00f3n del Cauca y el Ministerio de Educaci\u00f3n Nacional, en el marco de la Emergencia Social, Cultural y Econ\u00f3mica decretada por el Gobierno Nacional mediante el Decreto 982 de 1999 y el Decreto 1811 de 2017, se permite informar a la opini\u00f3n p\u00fablica:<\/p>\n<p style=\"text-align: justify;\">Que, desde hace varias d\u00e9cadas, los pueblos ind\u00edgenas venimos luchando para que el Estado Colombiano respete y garantice el derecho fundamental que tenemos a una Educaci\u00f3n Propia, adecuada y pertinente como requisito indispensable para poder seguir viviendo como pueblos originarios.<\/p>\n<p style=\"text-align: justify;\">Que, para ello durante los \u00faltimos cuarenta a\u00f1os, hemos construido un Sistema Educativo Propio, de acuerdo con nuestras particularidades sociales y culturales para garantizar el derecho a la educaci\u00f3n de los ni\u00f1os, las ni\u00f1as y la comunidad en general es indispensable contar con las garant\u00edas laborales de los dinamizadores pedag\u00f3gicos que la hacen posible.<\/p>\n<p style=\"text-align: justify;\">Que, el 02 de diciembre de 2023 en la sesi\u00f3n de la Comisi\u00f3n Mixta &#8211; Decreto 1811\/2017 se firm\u00f3 un acta de acuerdo entre el CRIC, el Ministerio de Educaci\u00f3n y la Secretar\u00eda de Educaci\u00f3n del Cauca, donde se comprometieron a realizar el nombramiento de 1842 dinamizadores pedag\u00f3gicos, 52 rectores, 20 coordinadores, 94 orientadores de apoyo pedag\u00f3gico y 28 docentes para educaci\u00f3n inicial, se\u00f1alando que los 2036 dinamizadores deb\u00edan tener listos sus actos administrativos al finalizar el primer semestre de 2025.<\/p>\n<p style=\"text-align: justify;\">Que, desde el a\u00f1o 2024 cuando el CRIC convoc\u00f3 al Ministerio de Educaci\u00f3n y a la Entidad Territorial de manera reiterativa para establecer la ruta del acuerdo en el marco del Decreto 1811\/2017 se ha generado dilaciones de parte de las instituciones para avanzar en el acuerdo del nombramiento de los dinamizadores pedag\u00f3gicos de la planta CRIC, incumplimientos que han sido verificados por la Defensor\u00eda del Pueblo y la Procuradur\u00eda General de la Naci\u00f3n desde el 9 de abril de 2024.<\/p>\n<p style=\"text-align: justify;\">Que, en la Mesa T\u00e9cnica del d\u00eda 29 de abril del 2025 encabezada por la Secretaria de Educaci\u00f3n del departamento, Dra. Sor In\u00e9s Larrahondo y Luz Adriana Quintero, Subdirectora de Recursos Humanos del Sector Educativo del Ministerio de Educaci\u00f3n Nacional, no hubo voluntad pol\u00edtica para viabilizar integralmente el cumplimiento del acuerdo del 2 de diciembre de 2023, desconociendo en algunas intervenciones los compromisos adquiridos y los derechos que nos asisten como pueblos ind\u00edgenas.<\/p>\n<p style=\"text-align: justify;\">\nQue, a la fecha s\u00f3lo se han nombrado 262 dinamizadores de un total de 2036 y pese a los compromisos establecidos en esta Mesa T\u00e9cnica para avanzar en esta ruta de nombramiento con la notificaci\u00f3n de 285 dinamizadores en el mes de mayo y 485 al mes de julio del a\u00f1o 2025, estas acciones son insuficientes frente al rezago de 1031 nombramientos que quedan a\u00fan pendientes y sin una ruta clara para su definici\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En este sentido, ante el fracaso para llegar a acuerdos con las funcionarias respectivas, vemos necesario suspender la Mesa T\u00e9cnica y escalar la discusi\u00f3n con representantes del Ministerio de Educaci\u00f3n Nacional y la Secretar\u00eda de Educaci\u00f3n del Departamento del Cauca con poder de decisi\u00f3n, que posibiliten viabilizar el cumplimiento de la Ruta para el nombramiento de los dinamizadores.<\/p>\n<p style=\"text-align: justify;\">Con estas acciones de dilaci\u00f3n a los compromisos y acuerdos pactados en el marco del Decreto 1811\/2017, es evidente para los pueblos ind\u00edgenas que no existen las garant\u00edas necesarias de proteger el derecho fundamental a la educaci\u00f3n de los ni\u00f1os y las ni\u00f1as, operativizar el Sistema Educativo Ind\u00edgena Propio y posibilitar las garant\u00edas laborales de los dinamizadores pedag\u00f3gicos ind\u00edgenas pertenecientes al Consejo Regional Ind\u00edgena del Cauca \u2013 CRIC.<\/p>\n<p style=\"text-align: justify;\">Ante esta situaci\u00f3n, las Autoridades Tradicionales de los 11 pueblos ind\u00edgenas agrupados en el CRIC, nos declaramos en ASAMBLEA PERMANENTE; y en consecuencia, convocamos de manera urgente al Gobernador del Cauca, Dr. Octavio Guzm\u00e1n y al Ministro de Educaci\u00f3n, Dr. Daniel Rojas, para el d\u00eda 6 de mayo, en el espacio de di\u00e1logo comunitario, del territorio ancestral de Kweth Kina-El Pital, en el municipio de Caldono. Exigimos en este espacio una respuesta efectiva a los compromisos adquiridos por el Ministerio de Educaci\u00f3n Nacional y la Secretar\u00eda de Educaci\u00f3n del Departamento del Cauca.<\/p>\n<p style=\"text-align: justify;\">Solicitamos al Ministerio Publico (Defensor\u00eda del Pueblo, Procuradur\u00eda General de la Republica), a los organismos Internacionales (Naciones Unidas, MAP-OEA) como garantes de nuestros derechos fundamentales, estar atentos, hacer seguimiento y solicitar al Gobierno Nacional el cumplimiento de los acuerdos con los Pueblos Ind\u00edgenas del Cauca.<\/p>\n<p style=\"text-align: center;\">\n<strong>CONSEJERIA MAYOR<\/strong><br \/>\n<strong>CONSEJO REGIONAL IND\u00cdGENA DEL CAUCA &#8211; CRIC-<\/strong><\/p>\n<p style=\"text-align: center;\">\nPopay\u00e1n, 30 de abril del 2025<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2025\/04\/COMUNICADO-A-LA-OPINION-PUBLICA.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"off\">COMUNICADO A LA OPINI\u00d3N P\u00daBLICA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunicado a la Opini\u00f3n P\u00fablica Nacional e Internacional El Consejo Regional Ind\u00edgena del Cauca CRIC, con sus 138 autoridades tradicionales y 11 Asociaciones de cabildos pertenecientes a once Pueblos Ind\u00edgenas (Totoroez, Nasas, Misak, Kokonukos, Yanakonas Polindara, Ampiule, Kisgo, Eperara-Siapirara, Inga), ante el incumplimiento sistem\u00e1tico de parte de la Secretar\u00eda de Educaci\u00f3n de la Gobernaci\u00f3n del <\/p>\n","protected":false},"author":13,"featured_media":36596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,23],"tags":[329,429,198,253,1216,1215,561,398],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017 - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017 - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"Comunicado a la Opini\u00f3n P\u00fablica Nacional e Internacional El Consejo Regional Ind\u00edgena del Cauca CRIC, con sus 138 autoridades tradicionales y 11 Asociaciones de cabildos pertenecientes a once Pueblos Ind\u00edgenas (Totoroez, Nasas, Misak, Kokonukos, Yanakonas Polindara, Ampiule, Kisgo, Eperara-Siapirara, Inga), ante el incumplimiento sistem\u00e1tico de parte de la Secretar\u00eda de Educaci\u00f3n de la Gobernaci\u00f3n del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-30T21:50:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2023\/02\/logo-cric-52-a\u00f1os-4-principios500x500.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pccriceditor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pccriceditor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/\"},\"author\":{\"name\":\"pccriceditor\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60\"},\"headline\":\"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017\",\"datePublished\":\"2025-04-30T21:50:37+00:00\",\"dateModified\":\"2025-04-30T21:50:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/\"},\"wordCount\":859,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"keywords\":[\"Acuerdos\",\"Bogota\",\"comunicado\",\"Educacion\",\"incumplimiento\",\"ministerio\",\"propia\",\"SEIP\"],\"articleSection\":[\"Actualidad Ind\u00edgena del Cauca\",\"Actualidad Ind\u00edgena Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/\",\"name\":\"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017 - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2025-04-30T21:50:37+00:00\",\"dateModified\":\"2025-04-30T21:50:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60\",\"name\":\"pccriceditor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g\",\"caption\":\"pccriceditor\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/pccriceditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017 - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/","og_locale":"es_ES","og_type":"article","og_title":"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017 - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"Comunicado a la Opini\u00f3n P\u00fablica Nacional e Internacional El Consejo Regional Ind\u00edgena del Cauca CRIC, con sus 138 autoridades tradicionales y 11 Asociaciones de cabildos pertenecientes a once Pueblos Ind\u00edgenas (Totoroez, Nasas, Misak, Kokonukos, Yanakonas Polindara, Ampiule, Kisgo, Eperara-Siapirara, Inga), ante el incumplimiento sistem\u00e1tico de parte de la Secretar\u00eda de Educaci\u00f3n de la Gobernaci\u00f3n del","og_url":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2025-04-30T21:50:37+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2023\/02\/logo-cric-52-a\u00f1os-4-principios500x500.png","type":"image\/png"}],"author":"pccriceditor","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"pccriceditor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/"},"author":{"name":"pccriceditor","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60"},"headline":"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017","datePublished":"2025-04-30T21:50:37+00:00","dateModified":"2025-04-30T21:50:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/"},"wordCount":859,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"keywords":["Acuerdos","Bogota","comunicado","Educacion","incumplimiento","ministerio","propia","SEIP"],"articleSection":["Actualidad Ind\u00edgena del Cauca","Actualidad Ind\u00edgena Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/","url":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/","name":"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017 - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2025-04-30T21:50:37+00:00","dateModified":"2025-04-30T21:50:37+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/mineducacion-y-secretaria-de-educacion-del-cauca-incumplen-acuerdos-realizados-en-el-marco-del-decreto-1811-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"MinEducaci\u00f3n y Secretar\u00eda de Educaci\u00f3n del Cauca incumplen acuerdos realizados en el marco del Decreto 1811\/2017"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60","name":"pccriceditor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g","caption":"pccriceditor"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/pccriceditor\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2023\/02\/logo-cric-52-a\u00f1os-4-principios500x500.png","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/42319"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=42319"}],"version-history":[{"count":1,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/42319\/revisions"}],"predecessor-version":[{"id":42321,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/42319\/revisions\/42321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/36596"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=42319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=42319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=42319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}