{"id":41901,"date":"2025-02-20T21:07:53","date_gmt":"2025-02-21T02:07:53","guid":{"rendered":"https:\/\/www.cric-colombia.org\/portal\/?p=41901"},"modified":"2025-02-21T11:36:33","modified_gmt":"2025-02-21T16:36:33","slug":"comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/","title":{"rendered":"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">Recientemente fuimos conocedores y conocedoras de una carta p\u00fablica de renuncia y denuncia por acoso sexual y laboral por parte de la compa\u00f1era Sandra Milena Cobos, donde se responsabiliza al viceministro de los Pueblos \u00c9tnicos y Campesinos, Nelson Lemus, quien ha sido parte de nuestros procesos pol\u00edtico &#8211; organizativos, como exconsejero zonal y regional, exautoridad y comunero ind\u00edgena.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Durante estos a\u00f1os, nuestra organizaci\u00f3n se ha sumado a las diversas voces que reclaman justicia frente a hechos que vulneran la tranquilidad y el buen vivir de nuestros pueblos, en general, y las <strong>desarmon\u00edas que afectan a las mujeres, j\u00f3venes y ni\u00f1as, en particular.<\/strong> Hemos reconocido que muchas de estas desarmon\u00edas no son externas sino que, lastimosamente, tambi\u00e9n ocurren en nuestros territorios y comunidades. Por eso, hemos venido construyendo estrategias y propuestas de prevenci\u00f3n, atenci\u00f3n, remedio y no repetici\u00f3n de estas desarmon\u00edas y violencias f\u00edsicas, sexuales, psicol\u00f3gicas, econ\u00f3micas y culturales hacia las mujeres en el marco del derecho propio y, en varios casos, en ejercicios de coordinaci\u00f3n con la justicia ordinaria.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Lamentamos profundamente que las violencias hacia las mujeres contin\u00faen ocurriendo y abogamos porque los presuntos hechos expuestos anteriormente cuenten con todas las garant\u00edas para el proceso de investigaci\u00f3n y la identificaci\u00f3n de responsabilidades y sanciones a las que haya lugar. Nos parece fundamental que haya garant\u00edas para que los casos no queden en la impunidad y sea alcanzada la justicia. <\/strong><\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Reafirmamos, una vez m\u00e1s, que nuestra apuesta de Buen Vivir debe garantizar que todos los seres tengan<strong> derecho a una vida libre de violencias en todas sus formas.<\/strong> De la misma manera, insistimos en que quienes ostentan cargos de autoridad y liderazgo deben, en raz\u00f3n de la dignidad de los cargos que les confieren las autoridades, dar ejemplo y encausar sus acciones hacia la garant\u00eda de los derechos de los pueblos ind\u00edgenas y de las mujeres ind\u00edgenas. Sin duda, esto hace parte de la lucha por la armon\u00eda para todos y todas en nuestros territorios y en todos los espacios que ocupamos.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">As\u00ed mismo, como organizaci\u00f3n, nos mantenemos en reafirmar nuestro <strong>compromiso por una vida digna, segura y libre de todas las formas de violencias hacia las mujeres, j\u00f3venes y ni\u00f1as ind\u00edgenas<\/strong> en sus casas, familias, comunidades, caminos, instituciones educativas, procesos organizativos y laborales.<\/p>\n<p style=\"font-weight: 400; text-align: center;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2025\/02\/PRONUNCIAMIENTO-NELSON-LEMUS-FEBRERO-I.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"off\">PRONUNCIAMIENTO NELSON LEMUS FEBRERO I<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recientemente fuimos conocedores y conocedoras de una carta p\u00fablica de renuncia y denuncia por acoso sexual y laboral por parte de la compa\u00f1era Sandra Milena Cobos, donde se responsabiliza al viceministro de los Pueblos \u00c9tnicos y Campesinos, Nelson Lemus, quien ha sido parte de nuestros procesos pol\u00edtico &#8211; organizativos, como exconsejero zonal y regional, exautoridad <\/p>\n","protected":false},"author":13,"featured_media":36596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,23,19],"tags":[198,347,651],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"Recientemente fuimos conocedores y conocedoras de una carta p\u00fablica de renuncia y denuncia por acoso sexual y laboral por parte de la compa\u00f1era Sandra Milena Cobos, donde se responsabiliza al viceministro de los Pueblos \u00c9tnicos y Campesinos, Nelson Lemus, quien ha sido parte de nuestros procesos pol\u00edtico &#8211; organizativos, como exconsejero zonal y regional, exautoridad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-21T02:07:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T16:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2023\/02\/logo-cric-52-a\u00f1os-4-principios500x500.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pccriceditor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pccriceditor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/\"},\"author\":{\"name\":\"pccriceditor\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60\"},\"headline\":\"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer\",\"datePublished\":\"2025-02-21T02:07:53+00:00\",\"dateModified\":\"2025-02-21T16:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/\"},\"wordCount\":442,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"keywords\":[\"comunicado\",\"Mujeres\",\"violencia\"],\"articleSection\":[\"Actualidad Ind\u00edgena del Cauca\",\"Actualidad Ind\u00edgena Nacional\",\"Comunicados de prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/\",\"name\":\"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2025-02-21T02:07:53+00:00\",\"dateModified\":\"2025-02-21T16:36:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60\",\"name\":\"pccriceditor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g\",\"caption\":\"pccriceditor\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/pccriceditor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/","og_locale":"es_ES","og_type":"article","og_title":"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"Recientemente fuimos conocedores y conocedoras de una carta p\u00fablica de renuncia y denuncia por acoso sexual y laboral por parte de la compa\u00f1era Sandra Milena Cobos, donde se responsabiliza al viceministro de los Pueblos \u00c9tnicos y Campesinos, Nelson Lemus, quien ha sido parte de nuestros procesos pol\u00edtico &#8211; organizativos, como exconsejero zonal y regional, exautoridad","og_url":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2025-02-21T02:07:53+00:00","article_modified_time":"2025-02-21T16:36:33+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2023\/02\/logo-cric-52-a\u00f1os-4-principios500x500.png","type":"image\/png"}],"author":"pccriceditor","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"pccriceditor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/"},"author":{"name":"pccriceditor","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60"},"headline":"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer","datePublished":"2025-02-21T02:07:53+00:00","dateModified":"2025-02-21T16:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/"},"wordCount":442,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"keywords":["comunicado","Mujeres","violencia"],"articleSection":["Actualidad Ind\u00edgena del Cauca","Actualidad Ind\u00edgena Nacional","Comunicados de prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/","url":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/","name":"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2025-02-21T02:07:53+00:00","dateModified":"2025-02-21T16:36:33+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/comunicado-a-la-opinion-publica-por-una-vida-digna-y-libre-de-violencias-hacia-la-mujer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Comunicado a la opini\u00f3n p\u00fablica: Por una vida digna y libre de violencias hacia la mujer"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/78004c978cf4d1d5326b7078c16b0e60","name":"pccriceditor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e693116508ed673b246753044786757b?s=96&d=retro&r=g","caption":"pccriceditor"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/pccriceditor\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2023\/02\/logo-cric-52-a\u00f1os-4-principios500x500.png","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/41901"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=41901"}],"version-history":[{"count":4,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/41901\/revisions"}],"predecessor-version":[{"id":41908,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/41901\/revisions\/41908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/36596"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=41901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=41901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=41901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}