{"id":32335,"date":"2021-11-08T21:24:26","date_gmt":"2021-11-09T02:24:26","guid":{"rendered":"https:\/\/www.cric-colombia.org\/portal\/?p=32335"},"modified":"2021-11-08T21:24:26","modified_gmt":"2021-11-09T02:24:26","slug":"atentan-contra-la-vida-de-exgobernador-indigena","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/","title":{"rendered":"Atentan contra la vida de exgobernador ind\u00edgena."},"content":{"rendered":"<p>En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca.<\/p>\n<p>Seg\u00fan informaci\u00f3n de las autoridades ind\u00edgenas del territorio Sath Tama Kiwe, dos sujetos armados que se encontraban sobre la v\u00eda, intentaron detener el veh\u00edculo en el cual viajaba el mayor Ovidio Hurtado con su familia y su esquema se seguridad, situaci\u00f3n que llamo la atenci\u00f3n, pues seg\u00fan se indic\u00f3, la seguridad al percatarse de que los sujetos en la v\u00eda estaban armados, no se detuvieron, lo que ocasion\u00f3 que les disparan, impactando el veh\u00edculo en el que viajaban en repetidas ocasiones.<\/p>\n<p>En el lamentable hecho, afortunadamente el exgobernador ind\u00edgena Ovidio Hurtado y sus acompa\u00f1antes salieron ilesos. Inmediatamente se conoci\u00f3 sobre el atentado, la Guardia Ind\u00edgena de Sath Tama Kiwe dispuso de un dispositivo para ubicar a los violentos que, al parecer, hacen parte de la disidencia columna m\u00f3vil Dagoberto Ramos.<\/p>\n<p>Desde el Consejo Regional Ind\u00edgena del Cauca, CRIC, se rechaz\u00f3 de manera contundente este nuevo hecho de violencia que pone en riesgo la vida de los l\u00edderes y comuneros ind\u00edgenas, lo que nuevamente pone en evidencia la falta de garant\u00edas a los derechos humanos y la pervivencia de los pueblos originarios de este pa\u00eds.<\/p>\n<p>\u201cEn el 2018 se registraron 26 homicidios, en el 2019 fueron 108, en el 2020 se contaron 106, y en lo que llevamos de este 2021, son 81 los comuneros y l\u00edderes asesinados en el Cauca. Es una situaci\u00f3n complicada, rechazamos la ola de violencia en nuestros territorios y exigimos al Gobierno Nacional que nos d\u00e9 las garant\u00edas\u201d expres\u00f3 Mauricio Capaz, consejero mayor del CRIC, de la zona norte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca. Seg\u00fan informaci\u00f3n de las autoridades ind\u00edgenas del territorio Sath Tama <\/p>\n","protected":false},"author":6,"featured_media":32336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[241,89,189,88,87,205],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Atentan contra la vida de exgobernador ind\u00edgena. - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"description\" content=\"En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atentan contra la vida de exgobernador ind\u00edgena. - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-09T02:24:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-08-at-6.54.43-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Atentan contra la vida de exgobernador ind\u00edgena.\",\"datePublished\":\"2021-11-09T02:24:26+00:00\",\"dateModified\":\"2021-11-09T02:24:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/\"},\"wordCount\":323,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"keywords\":[\"asesinato\",\"cauca\",\"CONSEJO REGIONAL INDIGENA DEL CAUCA CRIC\",\"cric\",\"indigenas\",\"norte cauca\"],\"articleSection\":[\"Actualidad Ind\u00edgena del Cauca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/\",\"name\":\"Atentan contra la vida de exgobernador ind\u00edgena. - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2021-11-09T02:24:26+00:00\",\"dateModified\":\"2021-11-09T02:24:26+00:00\",\"description\":\"En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atentan contra la vida de exgobernador ind\u00edgena.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atentan contra la vida de exgobernador ind\u00edgena. - Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/","og_locale":"es_ES","og_type":"article","og_title":"Atentan contra la vida de exgobernador ind\u00edgena. - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca.","og_url":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2021-11-09T02:24:26+00:00","og_image":[{"width":960,"height":1280,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-08-at-6.54.43-PM.jpeg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Atentan contra la vida de exgobernador ind\u00edgena.","datePublished":"2021-11-09T02:24:26+00:00","dateModified":"2021-11-09T02:24:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/"},"wordCount":323,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"keywords":["asesinato","cauca","CONSEJO REGIONAL INDIGENA DEL CAUCA CRIC","cric","indigenas","norte cauca"],"articleSection":["Actualidad Ind\u00edgena del Cauca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/","url":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/","name":"Atentan contra la vida de exgobernador ind\u00edgena. - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2021-11-09T02:24:26+00:00","dateModified":"2021-11-09T02:24:26+00:00","description":"En alerta se encuentran las comunidades ind\u00edgenas del Cauca despu\u00e9s de que, en horas de la tarde del ocho de noviembre, el dirigente ind\u00edgena Ovidio Hurtado, sufriera un atentado contra su vida en la vereda Santa Helena, en el municipio de Caldono, nororiente del Cauca.","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/atentan-contra-la-vida-de-exgobernador-indigena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Atentan contra la vida de exgobernador ind\u00edgena."}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-08-at-6.54.43-PM.jpeg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/32335"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=32335"}],"version-history":[{"count":1,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/32335\/revisions"}],"predecessor-version":[{"id":32337,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/32335\/revisions\/32337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/32336"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=32335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=32335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=32335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}