{"id":10668,"date":"2015-05-08T01:22:19","date_gmt":"2015-05-08T01:22:19","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=10668"},"modified":"2015-05-08T13:26:02","modified_gmt":"2015-05-08T13:26:02","slug":"urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/","title":{"rendered":"Urgente: fuerza publica atropella nuestra Comunidad de Paz"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/05\/Apartado.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-medium wp-image-10637\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/05\/Apartado-300x159.jpg\" alt=\"Apartado\" width=\"300\" height=\"159\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/05\/Apartado-300x159.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/05\/Apartado.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>&#8230;\u00bbEs de c\u00ednicos, acusar a tal nivel a quien ha acompa\u00f1ado y sufrido en carne propia el dolor de miles de victimas de la violencia en las ultimas d\u00e9cadas, simplemente porque ha entregado su voluntad al acompa\u00f1arnos en nuestro dolor, sufrimiento, enterrando muertos fustigados de un lado y del otro, y de nuestros hermanos en la comunidad que han ca\u00eddo por las balas de bestias asesinas, sometida a la miseria, marginada y sufrida por el flagelo de la violencia de los gobiernos de turno\u00bb&#8230;<!--more--><\/p>\n<p style=\"text-align: justify;\">El alto Gobierno persiste en su sordera infame, atizando mas cr\u00edmenes a los innumerables cometidos por la Fuerza P\u00fablica, que verg\u00fcenza, a ello se a\u00f1ade un manto de absoluta impunidad que lo encubre. Hace tan solo 3 d\u00edas, el pasado *domingo 3 de mayo de 2015*, el grupo elite de la Polic\u00eda Nacional, torturaba a varios civiles habitantes de la vereda la Hoz del corregimiento de San Jos\u00e9, que luego de varias horas de infamia, chantaje e intimidaci\u00f3n y ultrajes, fueron trasladados en helic\u00f3ptero quien sabe a donde. El atropello contra la poblaci\u00f3n civil campesina no para, y de<br \/>\nnuevo hoy se ensa\u00f1an contra nuestra Comunidad de Paz.<\/p>\n<p style=\"text-align: justify;\">El *lunes 4 de mayo de 2015*, nuestra comunidad tuvo informaci\u00f3n por parte de varios campesinos y habitantes del casco urbano de San Jos\u00e9, quienes han puesto en conocimiento de nuestra Comunidad de Paz, del asecho del que vienen siendo sometidos varios j\u00f3venes de la regi\u00f3n por parte de grupos paramilitares quienes los conminan a ingresar o trabajar para<br \/>\nellos, a varios de ellos, se los han llevado ofreci\u00e9ndoles trabajo en el Corregimiento de Piedras Blancas del Municipio de Apartad\u00f3, luego que llegan all\u00ed, les obligan a trabajar de paramilitar. Es de recordar que en Piedras Blancas, desde hace varios a\u00f1os es sometida al control<br \/>\nparamilitar, a pesar de la fuerte presencia de estamentos militares all\u00ed.<\/p>\n<p style=\"text-align: justify;\">El *martes 5 de mayo de 2015*, en varios medios de comunicaci\u00f3n nacionales, hicieron eco a los 77 puntos que el Senador \u00c1lvaro Uribe entrego a la Corte Suprema de Justicia, en el punto 69, el congresista acusa al Padre Giraldo, supuestamente, de esconder a terroristas y de gozar de impunidad blindada por su amistad e influencia en magistrados de la Corte.<br \/>\nEs de c\u00ednicos, acusar a tal nivel a quien ha acompa\u00f1ado y sufrido en carne propia el dolor de miles de victimas de la violencia en las ultimas d\u00e9cadas, simplemente porque ha entregado su voluntad al acompa\u00f1arnos en nuestro dolor, sufrimiento, enterrando muertos fustigados de un lado y del otro, y de nuestros hermanos en la comunidad que han ca\u00eddo por las balas de bestias asesinas, sometida a la miseria, marginada y sufrida por elflagelo de la violencia de los gobiernos de turno.<\/p>\n<p style=\"text-align: justify;\">El *mi\u00e9rcoles 6 de mayo de 2015,* hacia las 9:20 horas, en la vereda Mulatos del corregimiento de San Jos\u00e9, varios helic\u00f3pteros de la Polic\u00eda, que sobrevolaban el \u00e1rea, empezaron a desembarcar tropas de la Polic\u00eda Nacional Grupo Elite, justo en la Aldea de Paz Luis Eduardo Guerra, asentamiento de nuestra Comunidad de Paz, y territorio propiedad privada de la comunidad, lugar donde fue asesinado por el ejercito y los paramilitares el l\u00edder hist\u00f3rico de nuestra Comunidad de Paz, Luis Eduardo guerra en 21 de febrero de 2005. El sobrevuelo y la presencia de las tropas de la<br \/>\nPolic\u00eda han impedido el desarrollo de las actividades en nuestra escuelita comunitaria. Ya que los mismos agentes del Estado, prohibieron las actividades escolares. Es un atropello flagrante por parte de los uniformados, al violentar nuestros espacios de vida y trabajo de las familias, al interrumpir nuestras jornadas escolares, adem\u00e1s de convertir nuestras casas y \u00e1reas de recreaci\u00f3n de los ni\u00f1os en trincheras y helipuertos militares. Jam\u00e1s aceptaremos que nuestros espacios de vida, territorios de Paz, los conviertan en territorios de guerra.<\/p>\n<p style=\"text-align: justify;\">Acudimos nuevamente a la solidaridad nacional e internacional para que insten al Gobierno Nacional respetar nuestra vida, honra, integridad, seg\u00fan resoluci\u00f3n de la Corte Interamericana de Derechos Humanos y del derecho Internacional Humanitario consagrados en los tratados suscritos por el Estado Colombiano.<\/p>\n<p style=\"text-align: justify;\">Rechazamos terminantemente la presencia y la violaci\u00f3n de nuestros espacios y viviendas por parte de la fuerza publica, en un claro desacato al respeto de la propiedad privada consagrada en la constituci\u00f3n.<\/p>\n<p>Comunidad de Paz de San Jos\u00e9 de Apartad\u00f3<br \/>\nMayo 6 de 2015.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;\u00bbEs de c\u00ednicos, acusar a tal nivel a quien ha acompa\u00f1ado y sufrido en carne propia el dolor de miles de victimas de la violencia en las ultimas d\u00e9cadas, simplemente porque ha entregado su voluntad al acompa\u00f1arnos en nuestro dolor, sufrimiento, enterrando muertos fustigados de un lado y del otro, y de nuestros hermanos en <\/p>\n","protected":false},"author":6,"featured_media":10637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Urgente: fuerza publica atropella nuestra Comunidad de Paz - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Urgente: fuerza publica atropella nuestra Comunidad de Paz - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"&#8230;\u00bbEs de c\u00ednicos, acusar a tal nivel a quien ha acompa\u00f1ado y sufrido en carne propia el dolor de miles de victimas de la violencia en las ultimas d\u00e9cadas, simplemente porque ha entregado su voluntad al acompa\u00f1arnos en nuestro dolor, sufrimiento, enterrando muertos fustigados de un lado y del otro, y de nuestros hermanos en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-08T01:22:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-08T13:26:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/05\/Apartado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Urgente: fuerza publica atropella nuestra Comunidad de Paz\",\"datePublished\":\"2015-05-08T01:22:19+00:00\",\"dateModified\":\"2015-05-08T13:26:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/\"},\"wordCount\":752,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/\",\"name\":\"Urgente: fuerza publica atropella nuestra Comunidad de Paz - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2015-05-08T01:22:19+00:00\",\"dateModified\":\"2015-05-08T13:26:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Urgente: fuerza publica atropella nuestra Comunidad de Paz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Urgente: fuerza publica atropella nuestra Comunidad de Paz - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/","og_locale":"es_ES","og_type":"article","og_title":"Urgente: fuerza publica atropella nuestra Comunidad de Paz - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"&#8230;\u00bbEs de c\u00ednicos, acusar a tal nivel a quien ha acompa\u00f1ado y sufrido en carne propia el dolor de miles de victimas de la violencia en las ultimas d\u00e9cadas, simplemente porque ha entregado su voluntad al acompa\u00f1arnos en nuestro dolor, sufrimiento, enterrando muertos fustigados de un lado y del otro, y de nuestros hermanos en","og_url":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2015-05-08T01:22:19+00:00","article_modified_time":"2015-05-08T13:26:02+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/05\/Apartado.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Urgente: fuerza publica atropella nuestra Comunidad de Paz","datePublished":"2015-05-08T01:22:19+00:00","dateModified":"2015-05-08T13:26:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/"},"wordCount":752,"commentCount":1,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/","url":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/","name":"Urgente: fuerza publica atropella nuestra Comunidad de Paz - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2015-05-08T01:22:19+00:00","dateModified":"2015-05-08T13:26:02+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/urgente-fuerza-publica-atropella-nuestra-comunidad-de-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Urgente: fuerza publica atropella nuestra Comunidad de Paz"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/05\/Apartado.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10668"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=10668"}],"version-history":[{"count":1,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10668\/revisions"}],"predecessor-version":[{"id":10670,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10668\/revisions\/10670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/10637"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=10668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=10668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=10668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}