{"id":10585,"date":"2015-04-24T22:18:38","date_gmt":"2015-04-24T22:18:38","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=10585"},"modified":"2015-04-24T22:19:46","modified_gmt":"2015-04-24T22:19:46","slug":"por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/","title":{"rendered":"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Pueblos_Choco.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-medium wp-image-10587\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Pueblos_Choco-300x225.jpg\" alt=\"Pueblos_Choco\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Pueblos_Choco-300x225.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Pueblos_Choco.jpg 621w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La Organizaci\u00f3n Nacional Ind\u00edgena de Colombia \u2013 ONIC y la Asociaci\u00f3n de Cabildos Ind\u00edgenas del Choco \u2013 ASOREWA, RECHAZAMOS el asesinato de MELBA TEQUIA \u00a0SINTUA, mujer ind\u00edgena de la etnia Ember\u00e1 Kat\u00edo, en hechos ocurridos el d\u00eda 18 de abril del a\u00f1o en curso, por bombardeos realizados por el Ej\u00e9rcito Nacional, entre las 17:00 horas y las 23:00 horas de la fecha en menci\u00f3n, en territorio ind\u00edgena del Resguardo Tahami del Alto And\u00e1gueda y el Consejo Comunitario del Alto Atrato, Municipio de Bagad\u00f3.<!--more--><\/p>\n<p style=\"text-align: justify;\">Desde el mes de marzo de 2015 se evidencia el incremento y sistematicidad de bombardeos en los territorios colectivos del Alto And\u00e1gueda; siendo indiscutible que los graves eventos descritos, a todas luces infringen los criterios m\u00ednimos establecidos en instrumentos que reglamentan el Derecho Internacional Humanitario y son una clara vulneraci\u00f3n a est\u00e1ndares de Derechos Humanos de los Pueblos Ind\u00edgenas.<\/p>\n<p style=\"text-align: justify;\">No es la primera vez que bombardeos en cabeza de la Fuerza P\u00fablica, afectan de manera grave a comunidades ind\u00edgenas en el Choc\u00f3; en los \u00faltimos dos a\u00f1os, circunstancias id\u00e9nticas han ocasionado desplazamientos masivos y confinamientos que han sido denunciados de manera reiterada por nuestras organizaciones ante instancias nacionales e internacionales. Desafortunadamente las denuncias no han impedido que sigan persistiendo en acciones militares de esta naturaleza, las cuales implican un riesgo inminente para la vida e integridad personal de quienes habitan las zonas en las que se desarrollan las mismas.<\/p>\n<p style=\"text-align: justify;\">Al panorama anteriormente descrito, se suma la crisis humanitaria afrontada en los territorios ind\u00edgenas en el Choc\u00f3, siendo una realidad la muerte de centenares de Ember\u00e1s, sobre todo ni\u00f1os, ni\u00f1as, adolescentes, adultos mayores y mujeres en embarazo y lactante. Resulta triste evidenciar que las acciones y omisiones por parte del gobierno nacional est\u00e1n profundizando el riesgo de extinci\u00f3n f\u00edsica y cultural identificado en 2009 por la Corte Constitucional: el empobrecimiento y las acciones vulneratorias de derechos individuales y colectivos de los Pueblos Ind\u00edgenas son la espada de Damocles que pende sobre la pervivencia de las comunidades que habitan en el Alto And\u00e1gueda.<\/p>\n<p style=\"text-align: justify;\">El impacto ocasionado por las acciones b\u00e9licas indiscriminadas, las l\u00f3gicas guerreristas, el accionar de actores armados legales e ilegales y el incremento de hechos de violencia; est\u00e1n generando nuevos procesos de confinamiento y el riesgo inminente de desplazamiento masivo de familiares enteras del pueblo Ember\u00e1, algunas de los cuales retornaron a sus territorios en el marco de un precario proceso liderado por la Unidad de Atenci\u00f3n y Reparaci\u00f3n Integral para las V\u00edctimas y que con el recrudecimiento de la guerra es sus territorios no est\u00e1n encontrando elementos m\u00ednimos para garantizar la sostenibilidad del proceso efectuado.<\/p>\n<p style=\"text-align: justify;\">Sea del caso anotar, que la comunidad afectada es beneficiaria de la primera sentencia de restituci\u00f3n de tierras en favor de Pueblos Ind\u00edgenas. Mediante providencia 007 del 23 de septiembre \u00a02014, expedido por la Sala Especializada en Restituci\u00f3n de Tierras del Tribunal Superior de Antioquia, se emiten una serie de \u00f3rdenes encaminadas a salvaguardar sus derechos; sin embargo las mismas a la fecha han sido flagrantemente incumplidas por la institucionalidad concernida, escenario que pone en tela de juicio la voluntad pol\u00edtica e intensi\u00f3n del gobierno nacional de implementar la normatividad que protege a las v\u00edctimas del conflicto armado interno en Colombia.<\/p>\n<p style=\"text-align: justify;\">Dando cuenta de los hechos denunciados en los renglones precedentes, desde la Organizaci\u00f3n Nacional Ind\u00edgena de Colombia ONIC y la Asociaci\u00f3n de Cabildos Ind\u00edgenas del Choco ASOREWA, EXIGIMOS:<\/p>\n<p style=\"text-align: justify;\">Que las entidades competentes en instancias penales y disciplinarias, investiguen a profundidad y con car\u00e1cter urgente, eficiente e imparcial los hechos \u00a0que aqu\u00ed \u00a0se denuncian. Hacemos especial \u00e9nfasis en que los mismos deber\u00e1n ser de conocimiento de la justicia ordinaria en aras de evitar que una vez m\u00e1s la impunidad impida el esclarecimiento de eventos vulneratorios de los derechos de los Pueblos Ind\u00edgenas en nuestro pa\u00eds.<br \/>\nQue todas las instancias competentes investiguen a las Fuerzas Militares por la sistematicidad de las vulneraciones a los derechos humanos e infracciones al derecho Internacional humanitarios que hemos venido denunciando, con las cuales se incumplen instrumentos internacionales ratificados total o parcialmente y las \u00f3rdenes judiciales como la Sentencia 007 del 23 de septiembre<br \/>\nExigimos al Estado Colombiano que se reparen inmediatamente los da\u00f1os morales, f\u00edsicos, culturales y comunitarios ocasionados por las acciones violentas del Ej\u00e9rcito Colombiano.<br \/>\nCONVOCAMOS:<\/p>\n<p style=\"text-align: justify;\">A todas las organizaciones \u00a0y pueblos amigos a nivel Nacional e Internacional para que se solidaricen con la grav\u00edsima situaci\u00f3n afrontada por los Pueblos Ind\u00edgenas en Colombia, \u00a0rechazando los hechos denunciados, ante los organismos defensoras de Derechos Humanos, pa\u00edses, Cortes Internacionales, entre otros y requiriendo al Estado Colombiano la cesaci\u00f3n de bombardeos y acciones b\u00e9licas en general en territorios ind\u00edgenas.<br \/>\nA todas las agencias de Naciones Unidas, Cruz Roja Internacional, Frente Amplio por la Paz, Defensor\u00eda del Pueblo, Procuradur\u00eda General de la Naci\u00f3n, Alta Consejer\u00eda Presidencial para los Derechos Humanos, entre otras; para que se constituya una comisi\u00f3n de verificaci\u00f3n humanitaria en la zona con fundamento en los hechos previamente relacionados.<\/p>\n<p style=\"text-align: center;\"><strong>\u00a1YO PORTO EL BAST\u00d3N DE LA PAZ!<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>AUTORIDAD NACIONAL DE GOBIERNO IND\u00cdGENA \u2013ONIC\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CONSEJO DE AUTORIDADES IND\u00cdGENAS \u2013 ASOCIACI\u00d3N DE CABILDOS IND\u00cdGENAS DEL CHOCO- ASOREWA<\/strong><\/p>\n<p>http:\/\/choco.org\/index.php\/informativo\/292-por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Organizaci\u00f3n Nacional Ind\u00edgena de Colombia \u2013 ONIC y la Asociaci\u00f3n de Cabildos Ind\u00edgenas del Choco \u2013 ASOREWA, RECHAZAMOS el asesinato de MELBA TEQUIA \u00a0SINTUA, mujer ind\u00edgena de la etnia Ember\u00e1 Kat\u00edo, en hechos ocurridos el d\u00eda 18 de abril del a\u00f1o en curso, por bombardeos realizados por el Ej\u00e9rcito Nacional, entre las 17:00 horas <\/p>\n","protected":false},"author":6,"featured_media":10587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"La Organizaci\u00f3n Nacional Ind\u00edgena de Colombia \u2013 ONIC y la Asociaci\u00f3n de Cabildos Ind\u00edgenas del Choco \u2013 ASOREWA, RECHAZAMOS el asesinato de MELBA TEQUIA \u00a0SINTUA, mujer ind\u00edgena de la etnia Ember\u00e1 Kat\u00edo, en hechos ocurridos el d\u00eda 18 de abril del a\u00f1o en curso, por bombardeos realizados por el Ej\u00e9rcito Nacional, entre las 17:00 horas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-24T22:18:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-24T22:19:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Pueblos_Choco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"621\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda\",\"datePublished\":\"2015-04-24T22:18:38+00:00\",\"dateModified\":\"2015-04-24T22:19:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/\"},\"wordCount\":920,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/\",\"name\":\"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2015-04-24T22:18:38+00:00\",\"dateModified\":\"2015-04-24T22:19:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/","og_locale":"es_ES","og_type":"article","og_title":"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"La Organizaci\u00f3n Nacional Ind\u00edgena de Colombia \u2013 ONIC y la Asociaci\u00f3n de Cabildos Ind\u00edgenas del Choco \u2013 ASOREWA, RECHAZAMOS el asesinato de MELBA TEQUIA \u00a0SINTUA, mujer ind\u00edgena de la etnia Ember\u00e1 Kat\u00edo, en hechos ocurridos el d\u00eda 18 de abril del a\u00f1o en curso, por bombardeos realizados por el Ej\u00e9rcito Nacional, entre las 17:00 horas","og_url":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2015-04-24T22:18:38+00:00","article_modified_time":"2015-04-24T22:19:46+00:00","og_image":[{"width":621,"height":466,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Pueblos_Choco.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda","datePublished":"2015-04-24T22:18:38+00:00","dateModified":"2015-04-24T22:19:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/"},"wordCount":920,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/","url":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/","name":"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2015-04-24T22:18:38+00:00","dateModified":"2015-04-24T22:19:46+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/por-reactivacion-de-bombardeos-es-asesinada-mujer-indigena-en-el-alto-andagueda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Por reactivaci\u00f3n de bombardeos es asesinada mujer ind\u00edgena en el Alto And\u00e1gueda"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Pueblos_Choco.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10585"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=10585"}],"version-history":[{"count":2,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10585\/revisions"}],"predecessor-version":[{"id":10589,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10585\/revisions\/10589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/10587"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=10585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=10585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=10585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}