{"id":10555,"date":"2015-04-23T21:36:28","date_gmt":"2015-04-23T21:36:28","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=10555"},"modified":"2015-04-23T21:36:28","modified_gmt":"2015-04-23T21:36:28","slug":"colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/","title":{"rendered":"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-medium wp-image-10557\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo-300x176.jpg\" alt=\"Modelo_despojo\" width=\"300\" height=\"176\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo-300x176.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo.jpg 620w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>CON VIDEO).-En La Guajira colombiana, una regi\u00f3n situada al norte del pa\u00eds y hogar de\u00a0 uno de los mayores pueblos ind\u00edgenas de Colombia, los way\u00fau, se est\u00e1 produciendo un exterminio silencioso, del que muy pocos medios informan. Los way\u00fau est\u00e1n muriendo de sed y hambre porque una empresa minera y grandes propietarios agr\u00edcolas han privatizado el principal r\u00edo de la regi\u00f3n, el Rancher\u00eda, y los han dejado sin agua. Denuncian que ya han muerto de inanici\u00f3n y sed 14.000 (14 mil) ind\u00edgenas, especialmente ni\u00f1os y personas mayores. Incluimos al final de la nota, parte del documental \u201cEl r\u00edo que nos robaron\u201d del periodista colombiano Gonzalo Guill\u00e9n. El documental ser\u00e1 utilizado como prueba documental ante la Comisi\u00f3n Interamericana de Derechos Humanos. MM<!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Exterminan en silencio a la mayor naci\u00f3n ind\u00edgena de Colombia<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>El r\u00edo madre fue privatizado para el servicio de la industria agr\u00edcola y la explotaci\u00f3n del carb\u00f3n<\/em><\/strong><\/p>\n<p>Como los medios de comunicaci\u00f3n corporativos tienen sus prioridades informativas bien definidas y orientadas, especialmente contra Cuba, Venezuela u otros pa\u00edses que no se subordinan a Occidente; usted no sabr\u00e1 que la naci\u00f3n ind\u00edgena Way\u00fau [1], la mayor de Colombia, se muere de hambre y sed porque el r\u00edo madre de la regi\u00f3n donde radican fue represado y su agua privatizada para el servicio de la industria agr\u00edcola y la explotaci\u00f3n de la mina de carb\u00f3n -a cielo abierto- m\u00e1s grande del mundo. Por esa misma raz\u00f3n, ignorar\u00e1, seguramente, la denuncia que esta comunidad ha presentado ante la Comisi\u00f3n Interamericana de Derechos Humanos -CIDH-, de la OEA, con sede en Washington, por la violaci\u00f3n de sus derechos vitales fundamentales.<\/p>\n<p>Los datos que existen del crimen que se comete contra la etnia Way\u00fau no son precisos, informa la web lasdosorillas.com. Seg\u00fan esta fuente, en el extenso territorio que ocupan en el extremo Norte del pa\u00eds sudamericano, la naci\u00f3n de origen prehisp\u00e1nico carece de controles y presencia estatal colombiana. En cualquier caso, seg\u00fan Armando Valbuena, autoridad tradicional Way\u00fau, unos 14 mil ni\u00f1os de la etnia han muerto de inanici\u00f3n y la mortandad no se detiene.<\/p>\n<p>A todo esto hay que agregar que la escasa ayuda del gobierno colombiano a los Way\u00fau,\u00a0 no llega a los ind\u00edgenas. El caso del Programa de Alimentaci\u00f3n y Nutrici\u00f3n, en el que se invierten m\u00e1s 15 millones de d\u00f3lares, es un ejemplo. Buena parte de ese dinero \u2013 denuncian los voceros de los\u00a0 Way\u00fau, Armando Valbuena y Javier Rojas Uriana- se queda en redes de corrupci\u00f3n y termina siendo utilizado en las campa\u00f1as pol\u00edticas para la compra de votos. T\u00e9ngase en cuenta, adem\u00e1s, que La Guajira posee una poblaci\u00f3n de 500 mil habitantes y ha recibido, durante los \u00faltimos 20 a\u00f1os, m\u00e1s de mil millones de d\u00f3lares por la extracci\u00f3n de sus recursos naturales (carb\u00f3n y gas), adem\u00e1s del dinero que le corresponde cada a\u00f1o del presupuesto nacional. Pero ese dinero es robado por la corrupci\u00f3n que domina las administraciones p\u00fablicas locales.<\/p>\n<p>En medio de ese panorama, en febrero de este a\u00f1o cinco autoridades tradicionales ind\u00edgenas, a trav\u00e9s de su representante legal Javier Rojas Uriana, solicitaban a la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) que dictase medidas cautelares urgentes que les permitan recuperar el uso del \u00fanico r\u00edo que poseen para detener la actual mortandad por inanici\u00f3n de ni\u00f1os y adultos mayores. La acci\u00f3n pretende que el organismo interamericano ordene la apertura inmediata de las compuertas que restringen el paso del agua del r\u00edo Rancher\u00eda, que es acumulada en la represa El Cercado.<\/p>\n<p>Seg\u00fan la abogada S\u00e1chica Moreno, del Consultorio Jur\u00eddico de la Universidad de Bogot\u00e1, el agua del r\u00edo, un bien p\u00fablico, fue privatizado y la primera consecuencia de ello es el proceso de exterminio en que se encuentra esta etnia colombiana, sumida en la miseria y el abandono.<\/p>\n<p><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-10558\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_2-300x235.jpg\" alt=\"Modelo_despojo_2\" width=\"300\" height=\"235\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_2-300x235.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_2.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La cruda realidad para estos seres humanos es que la mayor parte del r\u00edo qued\u00f3 completamente seco, pues su caudal hoy est\u00e1 destinado exclusivamente a grandes haciendas del sur de La Guajira y a las operaciones industriales de las minas de carb\u00f3n de Cerrej\u00f3n.<\/p>\n<p>De acuerdo a la solicitud presentada ante la CIDH, la legislaci\u00f3n internacional y nacional, y a estudios de la Defensor\u00eda del Pueblo y la Contralor\u00eda General de la Rep\u00fablica de Colombia, los primeros destinatarios del agua deben ser siempre los seres humanos. Solamente despu\u00e9s de que ellos la tengan garantizada a satisfacci\u00f3n, los excedentes que resulten pueden ser usados en menesteres agr\u00edcolas, industriales y otros.<\/p>\n<p><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-10559\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_3-300x189.jpg\" alt=\"Modelo_despojo_3\" width=\"300\" height=\"189\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_3-300x189.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo_3.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Por otra parte, adem\u00e1s de pedir la apertura inmediata de las compuertas de la represa para que el agua llegue cuanto antes a los ind\u00edgenas, se pide que se ordene suspender de manera inmediata las tomas de agua de La Guajira que Cerrej\u00f3n obtiene de otras fuentes p\u00fablicas distintas al r\u00edo, principalmente subterr\u00e1neas, hasta que una evaluaci\u00f3n t\u00e9cnica id\u00f3nea e imparcial determine si, despu\u00e9s de abastecer satisfactoriamente a los seres humanos en la regi\u00f3n, quedan excedentes de agua para destinarlos a la agricultura a gran escala y a la explotaci\u00f3n de las minas.<\/p>\n<p>Finalmente, del conjunto de pruebas judiciales que ser\u00e1n presentadas a la Comisi\u00f3n se destaca el documental in\u00e9dito que acaba de terminar el periodista colombiano Gonzalo Guill\u00e9n, \u201cEl r\u00edo que se robaron\u201d, donde se testimonian los hechos denunciados a trav\u00e9s de im\u00e1genes sobrecogedoras de La Guajira y declaraciones de los protagonistas.<\/p>\n<p>[1] El Nobel de literatura colombiano Gabriel Garc\u00eda M\u00e1rquez tuvo linaje Way\u00fau por parte de madre y la influencia de esa cultura est\u00e1 presente en una buena parte de su obra.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.youtube.com\/watch?v=V0lSITRieDw\"><strong>El r\u00edo que se robaron &#8211; Privatizaci\u00f3n de r\u00edo provoca 14 mil muertes de ind\u00edgenas por inanici\u00f3n<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>JUAN ANDR\u00c9S P\u00c9REZ RODR\u00cdGUEZ \/ APORREA<\/p>\n<p>&nbsp;<\/p>\n<p>fuente:\u00a0 http:\/\/pajarorojo.com.ar\/?p=15233<\/p>\n<p>http:\/\/www.nasaacin.org\/informativo-nasaacin\/3-newsflash\/7546-colombia-exterminio-privatizan-un-r%C3%ADo-y-matan-de-hambre-a-14-mil-ind%C3%ADgenas<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CON VIDEO).-En La Guajira colombiana, una regi\u00f3n situada al norte del pa\u00eds y hogar de\u00a0 uno de los mayores pueblos ind\u00edgenas de Colombia, los way\u00fau, se est\u00e1 produciendo un exterminio silencioso, del que muy pocos medios informan. Los way\u00fau est\u00e1n muriendo de sed y hambre porque una empresa minera y grandes propietarios agr\u00edcolas han privatizado <\/p>\n","protected":false},"author":6,"featured_media":10557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"CON VIDEO).-En La Guajira colombiana, una regi\u00f3n situada al norte del pa\u00eds y hogar de\u00a0 uno de los mayores pueblos ind\u00edgenas de Colombia, los way\u00fau, se est\u00e1 produciendo un exterminio silencioso, del que muy pocos medios informan. Los way\u00fau est\u00e1n muriendo de sed y hambre porque una empresa minera y grandes propietarios agr\u00edcolas han privatizado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-23T21:36:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas\",\"datePublished\":\"2015-04-23T21:36:28+00:00\",\"dateModified\":\"2015-04-23T21:36:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/\"},\"wordCount\":1075,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/\",\"name\":\"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2015-04-23T21:36:28+00:00\",\"dateModified\":\"2015-04-23T21:36:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/","og_locale":"es_ES","og_type":"article","og_title":"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"CON VIDEO).-En La Guajira colombiana, una regi\u00f3n situada al norte del pa\u00eds y hogar de\u00a0 uno de los mayores pueblos ind\u00edgenas de Colombia, los way\u00fau, se est\u00e1 produciendo un exterminio silencioso, del que muy pocos medios informan. Los way\u00fau est\u00e1n muriendo de sed y hambre porque una empresa minera y grandes propietarios agr\u00edcolas han privatizado","og_url":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2015-04-23T21:36:28+00:00","og_image":[{"width":620,"height":363,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas","datePublished":"2015-04-23T21:36:28+00:00","dateModified":"2015-04-23T21:36:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/"},"wordCount":1075,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/","url":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/","name":"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2015-04-23T21:36:28+00:00","dateModified":"2015-04-23T21:36:28+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/colombia-exterminio-privatizan-un-rio-y-matan-de-hambre-a-14-mil-indigenas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Colombia-Exterminio: Privatizan un r\u00edo y matan de hambre a 14 mil ind\u00edgenas"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Modelo_despojo.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10555"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=10555"}],"version-history":[{"count":1,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10555\/revisions"}],"predecessor-version":[{"id":10560,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10555\/revisions\/10560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/10557"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=10555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=10555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=10555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}