{"id":10464,"date":"2015-04-09T23:33:01","date_gmt":"2015-04-09T23:33:01","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=10464"},"modified":"2015-04-09T23:33:01","modified_gmt":"2015-04-09T23:33:01","slug":"equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/","title":{"rendered":"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos  pedag\u00f3gicos"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-medium wp-image-10466\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_1-300x201.jpg\" alt=\"Zona_Occidente_Morales_1\" width=\"300\" height=\"201\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_1-300x201.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_1.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En el resguardo \u00a0ancestral de Honduras, vereda Mes\u00f3n se reunieron los rectores de las instituciones educativas de: Agua negra, Sek Walaca, Buscando Horizonte, Chimborazo, el Mes\u00f3n y junto con ellos, las autoridades zonales y la delegaci\u00f3n del rograma de Educaci\u00f3n Biling\u00fce Intercultural del CRIC.<\/p>\n<p style=\"text-align: justify;\">En el encuentro realizado los d\u00edas 6 y 7 de abril, se abordaron temas como; la socializaci\u00f3n de los alcances, dificultades y proyecciones en el desarrollo de los proyectos pedag\u00f3gicos, la implementaci\u00f3n del calendario propio, la coordinaci\u00f3n de tareas y proyecci\u00f3n de los procesos de comunicaci\u00f3n local y zonal.<!--more--><\/p>\n<p style=\"text-align: justify;\">En la actividad se destac\u00f3 el trabajo que se viene realizando en cada una de las instituciones educativas, teniendo en cuenta los proyectos pedag\u00f3gicos y productivos, los cuales se trabajan de manera\u00a0 permanente con los estudiantes y padres de familia, estas iniciativas \u00a0ayuda a tener una producci\u00f3n agr\u00edcola permanente, que beneficia\u00a0 a la misma poblaci\u00f3n estudiantil y comunidad, de igual manera permite realizar ejercicios pedag\u00f3gicos en\u00a0 clases y en la hora del campo. Contribuye a abordar las dificultades que se presenta en el proceso educativo sobre la perdida de la identidad cultural, la contaminaci\u00f3n a la madre tierra. En las instituciones mencionadas, se viene implementando la estrategia de formaci\u00f3n en el \u00e1rea de\u00a0 comunicaci\u00f3n y lenguaje enfocada a las radios escolares con el fin de realizar ejercicios pr\u00e1cticos para visibilizar a trav\u00e9s de los escritos, los audios visuales, mensajes de radio y la recuperaci\u00f3n de los procesos de \u00a0comunicaci\u00f3n propia las vivencias territoriales y comunitarias.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-10467\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_2-300x202.jpg\" alt=\"Zona_Occidente_Morales_2\" width=\"300\" height=\"202\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_2-300x202.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_2.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Wiliam Bermudez, rector de la instituci\u00f3n educativa del Mes\u00f3n mencion\u00f3: \u2026\u201c<em>Nos hemos proyectado fortalecer los procesos de educaci\u00f3n propia, identificando elementos que nos ayuden a conocer\u00a0 m\u00e1s sobre la ejecuci\u00f3n de los proyectos pedag\u00f3gicos de manera pr\u00e1ctica para que se fortalezcan los Proyectos Educativos Comunitarios PEC, los\u00a0 planes de vida de la comunidad y el sistema de <\/em> <em>educaci\u00f3n ind\u00edgena propio SEIP. Tambi\u00e9n se quiere hablar de proyectos pedag\u00f3gicos zonales como de la Asociaci\u00f3n Uh Wala Wic Kiwe de la Zona Occidente del territorio CRIC, el prop\u00f3sito es unificar los proyectos pedag\u00f3gicos como; la\u00a0 protecci\u00f3n\u00a0 y conservaci\u00f3n a la madre tierra, la autonom\u00eda alimentaria, la cosmovisi\u00f3n y el fortalecimiento de la lengua materna\u201d&#8230;<\/em><\/p>\n<p style=\"text-align: justify;\">Concluyendo el encuentro zonal, se agendaron actividades para continuar con los espacios permanentes de\u00a0 articulaci\u00f3n de trabajo entre instituciones educativas de la zona.<\/p>\n<p><a href=\"http:\/\/www.ivoox.com\/entrevista-william-bermudez-rector-institucion-educativa-meson-morales-audios-mp3_rf_4332210_1.html\"><strong>Entrevista_William_Berm\u00fadez_Rector_Instituci\u00f3n_Educativa_Mes\u00f3n_Morales<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><strong>PROGRAMA DE COMUNICACIONES Y EDUCACI\u00d3N BILING\u00dcE E INTERCULTURAL PEBI-CRIC<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el resguardo \u00a0ancestral de Honduras, vereda Mes\u00f3n se reunieron los rectores de las instituciones educativas de: Agua negra, Sek Walaca, Buscando Horizonte, Chimborazo, el Mes\u00f3n y junto con ellos, las autoridades zonales y la delegaci\u00f3n del rograma de Educaci\u00f3n Biling\u00fce Intercultural del CRIC. En el encuentro realizado los d\u00edas 6 y 7 de abril, <\/p>\n","protected":false},"author":6,"featured_media":10466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"En el resguardo \u00a0ancestral de Honduras, vereda Mes\u00f3n se reunieron los rectores de las instituciones educativas de: Agua negra, Sek Walaca, Buscando Horizonte, Chimborazo, el Mes\u00f3n y junto con ellos, las autoridades zonales y la delegaci\u00f3n del rograma de Educaci\u00f3n Biling\u00fce Intercultural del CRIC. En el encuentro realizado los d\u00edas 6 y 7 de abril,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-09T23:33:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos\",\"datePublished\":\"2015-04-09T23:33:01+00:00\",\"dateModified\":\"2015-04-09T23:33:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/\"},\"wordCount\":468,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena del Cauca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/\",\"name\":\"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2015-04-09T23:33:01+00:00\",\"dateModified\":\"2015-04-09T23:33:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/","og_locale":"es_ES","og_type":"article","og_title":"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"En el resguardo \u00a0ancestral de Honduras, vereda Mes\u00f3n se reunieron los rectores de las instituciones educativas de: Agua negra, Sek Walaca, Buscando Horizonte, Chimborazo, el Mes\u00f3n y junto con ellos, las autoridades zonales y la delegaci\u00f3n del rograma de Educaci\u00f3n Biling\u00fce Intercultural del CRIC. En el encuentro realizado los d\u00edas 6 y 7 de abril,","og_url":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2015-04-09T23:33:01+00:00","og_image":[{"width":600,"height":401,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_1.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos","datePublished":"2015-04-09T23:33:01+00:00","dateModified":"2015-04-09T23:33:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/"},"wordCount":468,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena del Cauca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/","url":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/","name":"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2015-04-09T23:33:01+00:00","dateModified":"2015-04-09T23:33:01+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/equipo-de-educacion-de-la-zona-occidente-municipio-de-morales-continua-fortaleciendo-los-proyectos-pedagogicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Equipo de educaci\u00f3n de la zona occidente municipio de Morales, contin\u00faa fortaleciendo los Proyectos pedag\u00f3gicos"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/04\/Zona_Occidente_Morales_1.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10464"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=10464"}],"version-history":[{"count":1,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10464\/revisions"}],"predecessor-version":[{"id":10468,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10464\/revisions\/10468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/10466"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=10464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=10464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=10464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}