{"id":10359,"date":"2015-03-21T18:28:27","date_gmt":"2015-03-21T18:28:27","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=10359"},"modified":"2015-03-21T18:28:27","modified_gmt":"2015-03-21T18:28:27","slug":"pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/","title":{"rendered":"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2013\/03\/Pueblo-Totoroez.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-4079\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2013\/03\/Pueblo-Totoroez-300x169.jpg\" alt=\"Pueblo Totoroez\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2013\/03\/Pueblo-Totoroez-300x169.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2013\/03\/Pueblo-Totoroez.jpg 901w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Desde el a\u00f1o 2009 como Pueblo ind\u00edgena Totoroez (Tont\u00b4tuna), en el marco de la sentencia de la corte constitucional Auto 004, iniciamos un proceso de diagn\u00f3stico sobre las secuelas que ha dejado el conflicto armado a trav\u00e9s de la historia en nuestro pueblo y a partir de este proceso, construir un plan de salvaguarda que nos garantice la pervivencia evitando nuestra extinci\u00f3n f\u00edsica y cultural.<!--more--><\/p>\n<p style=\"text-align: justify;\">En el a\u00f1o 2015, se cumplen ya seis (6) a\u00f1os durante los cuales se mantuvieron diversos acercamientos\u00a0 a trav\u00e9s de delegadas y delegados de las instituciones del gobierno nacional, los cuales en la mayor\u00eda de escenarios no tuvieron poder de decisi\u00f3n frente a los planteamientos del pueblo Totoroez, y menos en el eje de territorio, uno de los temas m\u00e1s urgentes de resolver para garantizar la pervivencia como pueblo.<\/p>\n<p style=\"text-align: justify;\">Para el pueblo Totoroez como para la mayor\u00eda de Pueblos Ind\u00edgenas \u00a0en Colombia, un ind\u00edgena\u00a0 sin territorio\u00a0 es considerado un ser incompleto. Por lo tanto estar\u00e1 siempre inquieto buscando esa parte tan fundamental que le permita existir a lado de su pueblo, interactuando y compartiendo con los suyos, dem\u00e1s seres naturales y sus formas de vida.<\/p>\n<p style=\"text-align: justify;\"><strong>Pensando en nuestras nuevas generaciones<\/strong><\/p>\n<p style=\"text-align: justify;\">Los d\u00edas 19 y 20 de marzo del a\u00f1o 2015, se hab\u00eda previsto un nuevo encuentro, con\u00a0 representantes de las instituciones del gobierno nacional, con el\u00a0 prop\u00f3sito de evaluar el estado actual del proceso del Auto 004, y con perspectivas de un avance efectivo hacia la implementaci\u00f3n del Plan Salva Guarda del pueblo Totoroez. Al verificar la asistencia de las instituciones, de las cincuenta y siete (57) que deber\u00edan asistir, llegaron Veintis\u00e9is (26) y la mayor\u00eda de ellas sin poder de decisi\u00f3n. Ante esta situaci\u00f3n la comunidad ind\u00edgena presente, solicito un espacio aut\u00f3nomo para analizar y decidir sobre lo que ha venido ocurriendo en los espacios de encuentro con los representantes de las instituciones del gobierno nacional, en el espacio aut\u00f3nomo, los ex gobernadores y mayores de la comunidad, reflexionaron en conjunto con la comunidad y manifestaron: Ya hemos \u00a0agotado los espacios de di\u00e1logo como instancias para concretar \u00a0acuerdos que permitan al\u00a0 Gobierno Nacional dar\u00a0 cumplimiento a la sentencia T-025 &#8211; Auto 004 de 2009, emitida por la Honorable Corte Constitucional \u00a0frente a la adopci\u00f3n de medidas de proteccion efectivas, que garanticen la pervivencia de los pueblos en riesgo de extinci\u00f3n f\u00edsica y cultural. Han pasado ya seis a\u00f1os y esto no ha sido posible, ya que por parte de las instituciones del Gobierno Nacional lo \u00fanico que brindan es la oferta Institucional, medidas que no corresponden a la garant\u00eda de protecci\u00f3n del pueblo Totoroez, ni de ning\u00fan pueblo en riego de exterminio f\u00edsico y cultural. Consideramos que se deben desarrollar e implementar pol\u00edticas de atenci\u00f3n integral a las comunidades por parte del Gobierno nacional, aparte de las medidas especiales que\u00a0 requiere el Plan de salva guarda.<\/p>\n<p style=\"text-align: justify;\"><strong>Por lo tanto definimos<\/strong>:<\/p>\n<p style=\"text-align: justify;\">1) Suspender\u00a0 los espacios de concertaci\u00f3n\u00a0 con el Gobierno Nacional,\u00a0 ya que desde reuniones anteriores hemos solicitado la presencia de los ministros, para obtener respuestas concretas ante las medidas a adoptar, sin embargo de ellos no volvimos a saber,\u00a0 desde\u00a0 el d\u00eda\u00a0 de la apertura realizada en el a\u00f1o 2009.<\/p>\n<p style=\"text-align: justify;\">2) Dar tiempo de un (1) \u00a0mes, \u00a0en el cual el Gobierno Nacional deber\u00e1 definir c\u00f3mo va a asumir con responsabilidad \u00a0y de manera efectiva la implementaci\u00f3n de los Planes Salva Guarda, que corresponda a las verdaderas necesidades planteadas desde los pueblos indigenas.<\/p>\n<p style=\"text-align: justify;\">3) Presentar un informe a la Corte Constitucional sobre el proceso adelantado hasta el momento, los motivos y los fundamentos de la decisi\u00f3n tomada como pueblo Totoroez.<\/p>\n<p style=\"text-align: justify;\">4) El Pueblo Ind\u00edgena Totor\u00f3ez \u00a0se declara \u00a0en asamblea\u00a0 permanente\u00a0 y en caso de no recibir respuesta positiva \u00a0por parte del Gobierno nacional en el tiempo estipulado, continuara con actividades leg\u00edtimas de \u00a0pervivencia.<\/p>\n<p style=\"text-align: justify;\">La Autoridad tradicional, continuara\u00a0 coordinando\u00a0 algunas\u00a0 actividades que no hacen parte del Plan de salvaguarda, las cuales han sido\u00a0 acordadas previamente\u00a0 en el marco de la institucionalidad\u00a0 con algunas entidades del gobierno.<\/p>\n<p style=\"text-align: justify;\">Agradecemos muy respetuosamente a las personas que en calidad de delegados de las instituciones del gobierno, hicieron presencia en los espacios de encuentro y trataron\u00a0 de hacer lo que estuvo a su alcance\u00a0 con miras de poder avanzar.<\/p>\n<p style=\"text-align: justify;\">\u201cNo queremos que las nuevas generaciones nos se\u00f1alen\u00a0 a quienes estamos hoy al frente del proceso organizativo, como los negociadores\u00a0 de\u00a0 nuestros\u00a0 derechos a cambio\u00a0 de proyectos\u201d<\/p>\n<p style=\"text-align: justify;\">Tenemos claro que la oferta institucional es una instancia \u00a0muy diferente \u00a0a las medidas que el Gobierno Nacional debe adoptar en\u00a0 el\u00a0 Plan \u00a0de salva guarda, para dar cumplimiento pleno a la sentencia de la Corte Constitucional Auto 004, con el fin de garantizar nuestra existencia f\u00edsica y cultural como pueblo.<\/p>\n<p><strong>AUTORIDAD TRADICIONAL <\/strong><\/p>\n<p><strong>CABILDO INDIGENA DEL PUEBLO TOTOROEZ<\/strong><\/p>\n<p><strong>VEREDA BETANIA\u00a0 MARZO 19 DE 2015<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el a\u00f1o 2009 como Pueblo ind\u00edgena Totoroez (Tont\u00b4tuna), en el marco de la sentencia de la corte constitucional Auto 004, iniciamos un proceso de diagn\u00f3stico sobre las secuelas que ha dejado el conflicto armado a trav\u00e9s de la historia en nuestro pueblo y a partir de este proceso, construir un plan de salvaguarda que <\/p>\n","protected":false},"author":6,"featured_media":4079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004 - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004 - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"Desde el a\u00f1o 2009 como Pueblo ind\u00edgena Totoroez (Tont\u00b4tuna), en el marco de la sentencia de la corte constitucional Auto 004, iniciamos un proceso de diagn\u00f3stico sobre las secuelas que ha dejado el conflicto armado a trav\u00e9s de la historia en nuestro pueblo y a partir de este proceso, construir un plan de salvaguarda que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-21T18:28:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2013\/03\/Pueblo-Totoroez.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"901\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004\",\"datePublished\":\"2015-03-21T18:28:27+00:00\",\"dateModified\":\"2015-03-21T18:28:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/\"},\"wordCount\":839,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena del Cauca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/\",\"name\":\"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004 - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2015-03-21T18:28:27+00:00\",\"dateModified\":\"2015-03-21T18:28:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004 - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/","og_locale":"es_ES","og_type":"article","og_title":"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004 - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"Desde el a\u00f1o 2009 como Pueblo ind\u00edgena Totoroez (Tont\u00b4tuna), en el marco de la sentencia de la corte constitucional Auto 004, iniciamos un proceso de diagn\u00f3stico sobre las secuelas que ha dejado el conflicto armado a trav\u00e9s de la historia en nuestro pueblo y a partir de este proceso, construir un plan de salvaguarda que","og_url":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2015-03-21T18:28:27+00:00","og_image":[{"width":"901","height":"510","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2013\/03\/Pueblo-Totoroez.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004","datePublished":"2015-03-21T18:28:27+00:00","dateModified":"2015-03-21T18:28:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/"},"wordCount":839,"commentCount":0,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena del Cauca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/","url":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/","name":"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004 - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2015-03-21T18:28:27+00:00","dateModified":"2015-03-21T18:28:27+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/pueblo-indigena-totoroez-suspende-dialogos-con-instituciones-del-gobierno-nacional-en-el-marco-del-auto-004\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Pueblo Ind\u00edgena Totoroez suspende di\u00e1logos con Instituciones del Gobierno Nacional en el marco del Auto 004"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2013\/03\/Pueblo-Totoroez.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10359"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=10359"}],"version-history":[{"count":1,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10359\/revisions"}],"predecessor-version":[{"id":10361,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10359\/revisions\/10361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/4079"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=10359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=10359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=10359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}