{"id":10187,"date":"2015-03-05T23:50:11","date_gmt":"2015-03-05T23:50:11","guid":{"rendered":"http:\/\/www.cric-colombia.org\/portal\/?p=10187"},"modified":"2015-03-05T23:51:08","modified_gmt":"2015-03-05T23:51:08","slug":"guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular","status":"publish","type":"post","link":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/","title":{"rendered":"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/03\/Gutemala_Encuentro_Mineria.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-medium wp-image-10189\" src=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/03\/Gutemala_Encuentro_Mineria-300x86.jpg\" alt=\"Gutemala_Encuentro_Mineria\" width=\"300\" height=\"86\" srcset=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/03\/Gutemala_Encuentro_Mineria-300x86.jpg 300w, https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/03\/Gutemala_Encuentro_Mineria.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La actividad minera a gran escala, por definici\u00f3n, es muy amplia en su apropiaci\u00f3n de la naturaleza y de los territorios. Esta apropiaci\u00f3n, con la expansi\u00f3n de la actividad minera tambi\u00e9n se expande y se esboza un mapa de los conflictos por justicia socioambiental en el continente. En una estructura de tierra tan desigual, como la que hay en la mayor parte de nuestro continente, los efectos de esta expansi\u00f3n son a\u00fan m\u00e1s perversos, donde, por ejemplo,\u00a0los emprendimientos comunitarios de la agricultura familiar, las tierras ind\u00edgenas, territorios afrodescendientes se eliminan del suelo en el nombre del subsuelo. \u00a0 <!--more--><\/p>\n<p style=\"text-align: justify;\">os conflictos se profundizan en este proceso y son varias consecuencias nefastas: despojo de los territorios; p\u00e9rdida de medios de vida y las din\u00e1micas territoriales asociados a la degradaci\u00f3n del medio ambiente; desterritorializaci\u00f3n; desplazamiento forzado; no viabilidad de la agricultura como consecuencia de la actividad minera; contaminaci\u00f3n de aguas superficiales y subterr\u00e1neas; militarizaci\u00f3n de los territorios; violaciones de los derechos humanos en general, especialmente en relaci\u00f3n con las mujeres directamente afectadas y los Pueblos Originarios;\u00a0en resumen los beneficiarios de la actividad minera, en la mayor\u00eda de los pa\u00edses de Nuestra Am\u00e9rica, son las empresas transnacionales, junto a las empresas nacionales asociadas a los capitales internacionales.<\/p>\n<p style=\"text-align: justify;\">En nuestros pa\u00edses, la demanda fundamental est\u00e1 vinculada a la capacidad de los pueblos por decidir la aceptaci\u00f3n o no de los proyectos mineros, las condiciones en las que se realizan y los beneficiarios de los mismos, en otras palabras, giran en torno a la soberan\u00eda de los pueblos para ser parte fundamental de la toma de decisiones.<\/p>\n<p style=\"text-align: justify;\">Pese a que las empresas transnacionales son las mismas con inversiones en distintos pa\u00edses del continente, las y los afectados por la miner\u00eda a\u00fan no hemos desarrollado las articulaciones necesarias para defender los derechos de nuestros pueblos. Es por esta raz\u00f3n que\u00a0ALBA MOVIMIENTOS[1]\u00a0se ha planteado la realizaci\u00f3n del Encuentro Continental contra la Miner\u00eda y por la Soberan\u00eda Popular, del 11 al 17 de Marzo de 2015, en el municipio de Mataquescuintla, en Guatemala, con los siguientes objetivos: 1. Profundizar en la comprensi\u00f3n sobre los distintos aspectos de la miner\u00eda en el continente.\u00a02.\u00a0Intercambiar informaci\u00f3n y experiencias de organizaci\u00f3n, lucha y movilizaci\u00f3n para fortalecer las luchas de resistencia frente a la miner\u00eda;\u00a03.\u00a0Establecer y dar a conocer nuestra posici\u00f3n y denuncias, como ALBA MOVIMIENTOS, ante los impactos de la miner\u00eda;\u00a04.\u00a0Contribuir a fortalecer las articulaciones existentes o la construcci\u00f3n de una articulaci\u00f3n continental a nivel de ALBA movimientos;\u00a05.\u00a0Avanzar en la definici\u00f3n e impulso de una estrategia y de una agenda com\u00fan de los movimientos sociales del Continente.<\/p>\n<p style=\"text-align: justify;\">PARTICIPANTES:\u00a0Nuestro objetivo es reunir cerca de 200 militantes y dirigentes de los movimientos sociales de todo el Continente, en particular, afectados por la miner\u00eda; representantes de pueblos y comunidades de pueblos originarios y campesinos; trabajadores que apoyan a los afectados por la miner\u00eda.<\/p>\n<p>PROGRAMA:<\/p>\n<table width=\"639\">\n<tbody>\n<tr>\n<td width=\"143\">11 de Marzo<\/td>\n<td width=\"570\">Llegada<\/td>\n<\/tr>\n<tr>\n<td width=\"143\">12 de Marzo<\/td>\n<td width=\"570\">An\u00e1lisis de coyuntura Continental y Panel \u201c\u201cLa l\u00f3gica del Modelo extractivo en el Continente\u201d<\/td>\n<\/tr>\n<tr>\n<td width=\"143\">13 de Marzo<\/td>\n<td width=\"570\">Visita a experiencias de Luchas Anti-mineras en Guatemala<\/td>\n<\/tr>\n<tr>\n<td width=\"143\">14 de Marzo<\/td>\n<td width=\"570\">Paneles Paralelos y Grupos de Trabajo<\/td>\n<\/tr>\n<tr>\n<td width=\"143\">15 de Marzo<\/td>\n<td width=\"570\">S\u00edntesis Pol\u00edtica del Encuentro y Declaraci\u00f3n Publica.Pr\u00f3ximos pasos Organizativos, Conclusiones y Acuerdos<\/td>\n<\/tr>\n<tr>\n<td width=\"143\">16 de Marzo<\/td>\n<td width=\"570\">Movilizaci\u00f3n Masiva en la Ciudad de Guatemala<\/td>\n<\/tr>\n<tr>\n<td width=\"143\">17 de Marzo<\/td>\n<td width=\"570\">Regreso de los Participantes<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><a href=\"http:\/\/vocesmayas.aler.org\/?p=2352\">http:\/\/vocesmayas.aler.org\/?p=2352<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actividad minera a gran escala, por definici\u00f3n, es muy amplia en su apropiaci\u00f3n de la naturaleza y de los territorios. Esta apropiaci\u00f3n, con la expansi\u00f3n de la actividad minera tambi\u00e9n se expande y se esboza un mapa de los conflictos por justicia socioambiental en el continente. En una estructura de tierra tan desigual, como <\/p>\n","protected":false},"author":6,"featured_media":10189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular - Consejo Regional Ind\u00edgena del Cauca - CRIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular - Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"og:description\" content=\"La actividad minera a gran escala, por definici\u00f3n, es muy amplia en su apropiaci\u00f3n de la naturaleza y de los territorios. Esta apropiaci\u00f3n, con la expansi\u00f3n de la actividad minera tambi\u00e9n se expande y se esboza un mapa de los conflictos por justicia socioambiental en el continente. En una estructura de tierra tan desigual, como\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Regional Ind\u00edgena del Cauca - CRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cric.colombia\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-05T23:50:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-05T23:51:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/03\/Gutemala_Encuentro_Mineria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"229\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones CRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:site\" content=\"@CRIC_Cauca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones CRIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/\"},\"author\":{\"name\":\"Comunicaciones CRIC\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\"},\"headline\":\"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular\",\"datePublished\":\"2015-03-05T23:50:11+00:00\",\"dateModified\":\"2015-03-05T23:51:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/\"},\"wordCount\":606,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"articleSection\":[\"Actualidad Ind\u00edgena Global\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/\",\"name\":\"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular - Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\"},\"datePublished\":\"2015-03-05T23:50:11+00:00\",\"dateModified\":\"2015-03-05T23:51:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cric-colombia.org\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#website\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca - CRIC\",\"description\":\"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia\",\"publisher\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#organization\",\"name\":\"Consejo Regional Ind\u00edgena del Cauca\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"contentUrl\":\"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consejo Regional Ind\u00edgena del Cauca\"},\"image\":{\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cric.colombia\/\",\"https:\/\/twitter.com\/CRIC_Cauca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931\",\"name\":\"Comunicaciones CRIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g\",\"caption\":\"Comunicaciones CRIC\"},\"url\":\"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular - Consejo Regional Ind\u00edgena del Cauca - CRIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/","og_locale":"es_ES","og_type":"article","og_title":"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular - Consejo Regional Ind\u00edgena del Cauca - CRIC","og_description":"La actividad minera a gran escala, por definici\u00f3n, es muy amplia en su apropiaci\u00f3n de la naturaleza y de los territorios. Esta apropiaci\u00f3n, con la expansi\u00f3n de la actividad minera tambi\u00e9n se expande y se esboza un mapa de los conflictos por justicia socioambiental en el continente. En una estructura de tierra tan desigual, como","og_url":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/","og_site_name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","article_publisher":"https:\/\/www.facebook.com\/cric.colombia\/","article_published_time":"2015-03-05T23:50:11+00:00","article_modified_time":"2015-03-05T23:51:08+00:00","og_image":[{"width":800,"height":229,"url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/03\/Gutemala_Encuentro_Mineria.jpg","type":"image\/jpeg"}],"author":"Comunicaciones CRIC","twitter_card":"summary_large_image","twitter_creator":"@CRIC_Cauca","twitter_site":"@CRIC_Cauca","twitter_misc":{"Escrito por":"Comunicaciones CRIC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#article","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/"},"author":{"name":"Comunicaciones CRIC","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931"},"headline":"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular","datePublished":"2015-03-05T23:50:11+00:00","dateModified":"2015-03-05T23:51:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/"},"wordCount":606,"commentCount":1,"publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"articleSection":["Actualidad Ind\u00edgena Global"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/","url":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/","name":"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular - Consejo Regional Ind\u00edgena del Cauca - CRIC","isPartOf":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#website"},"datePublished":"2015-03-05T23:50:11+00:00","dateModified":"2015-03-05T23:51:08+00:00","breadcrumb":{"@id":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cric-colombia.org\/portal\/guatemala-encuentro-continental-contra-la-mineria-y-por-la-soberania-popular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cric-colombia.org\/portal\/"},{"@type":"ListItem","position":2,"name":"Guatemala: Encuentro continental contra la miner\u00eda y por la soberania popular"}]},{"@type":"WebSite","@id":"https:\/\/www.cric-colombia.org\/portal\/#website","url":"https:\/\/www.cric-colombia.org\/portal\/","name":"Consejo Regional Ind\u00edgena del Cauca - CRIC","description":"P\u00e1gina oficial del Consejo Regional Ind\u00edgena del Cauca, Colombia","publisher":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cric-colombia.org\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cric-colombia.org\/portal\/#organization","name":"Consejo Regional Ind\u00edgena del Cauca","url":"https:\/\/www.cric-colombia.org\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","contentUrl":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/08\/logo_cric.jpg","width":512,"height":512,"caption":"Consejo Regional Ind\u00edgena del Cauca"},"image":{"@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cric.colombia\/","https:\/\/twitter.com\/CRIC_Cauca"]},{"@type":"Person","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/ab3a3099267de33d55f74f34ba201931","name":"Comunicaciones CRIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cric-colombia.org\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8d1a6cfcb82a80d09dafefdcc3dcc8a?s=96&d=retro&r=g","caption":"Comunicaciones CRIC"},"url":"https:\/\/www.cric-colombia.org\/portal\/author\/comunicaciones\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cric-colombia.org\/portal\/wp-content\/uploads\/2015\/03\/Gutemala_Encuentro_Mineria.jpg","_links":{"self":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10187"}],"collection":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/comments?post=10187"}],"version-history":[{"count":1,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10187\/revisions"}],"predecessor-version":[{"id":10190,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/posts\/10187\/revisions\/10190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media\/10189"}],"wp:attachment":[{"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/media?parent=10187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/categories?post=10187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cric-colombia.org\/portal\/wp-json\/wp\/v2\/tags?post=10187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}